{"id":155141,"date":"2020-06-30T11:31:15","date_gmt":"2020-06-30T11:31:15","guid":{"rendered":"https:\/\/blog.hannaservice.eu\/bestimmung-von-schwefeldioxid-in-wein\/"},"modified":"2022-10-11T08:12:18","modified_gmt":"2022-10-11T08:12:18","slug":"bestimmung-von-schwefeldioxid-in-wein","status":"publish","type":"post","link":"https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/","title":{"rendered":"Bestimmung von Schwefeldioxid in Wein"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"155141\" class=\"elementor elementor-155141 elementor-7975\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22008db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22008db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1727e8d\" data-id=\"1727e8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c92977f elementor-widget elementor-widget-text-editor\" data-id=\"c92977f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Beschreibung<\/h3>\n<p>Schwefeldioxid (SO2) ist ein weit verbreiteter Zusatzstoff in der Weinindustrie, um Oxidation und bakteriellen Verderb zu verhindern. Als Antioxidans tr\u00e4gt es dazu bei, die Farbe, den Geschmack und die Stabilit\u00e4t eines Weins zu erhalten. Schwefeldioxid wirkt antimikrobiell, indem es in die Stoffwechselwege von Hefe und Bakterien eingreift. Der Begriff \u201cfrei\u201d gibt die Menge an SO2 an, die zur Erf\u00fcllung dieser Funktionen zur Verf\u00fcgung steht. Der Rest des vorhandenen SO2 ist an andere Verbindungen \u201cgebunden\u201d und steht nicht zum Schutz des Weins zur Verf\u00fcgung. Diese beiden Elemente zusammengenommen stellen den \u201cGesamtgehalt\u201d an SO2 im Wein dar. Der Gehalt an freiem und Gesamtschwefeldioxid in einem fertigen Wein variiert je nach Stil, der pers\u00f6nlichen Philosophie des Winzers und allen gesetzlichen und beh\u00f6rdlichen Anforderungen.<\/p>\n<p>Die Ripper-Methode ist eine Titration, die von Winzern auf der ganzen Welt verwendet wird, um die Menge des im Wein vorhandenen SO2 zu verstehen. Obwohl sie im Prinzip einfach ist, kann sie doch recht arbeits- und zeitintensiv sein, insbesondere wenn viele Proben zu testen sind.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-506eb6d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"506eb6d2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7232a681\" data-id=\"7232a681\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a2cbe30 elementor-widget elementor-widget-text-editor\" data-id=\"2a2cbe30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-38888 lazyloaded\" src=\"https:\/\/hannaservice.eu\/wp-content\/uploads\/HI84500_2100x2100-800x800.jpg\" sizes=\"(max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/hannainstruments.at\/wp-content\/uploads\/HI84500_2100x2100-800x800.jpg 800w, https:\/\/hannainstruments.at\/wp-content\/uploads\/HI84500_2100x2100-400x400.jpg 400w, https:\/\/hannainstruments.at\/wp-content\/uploads\/HI84500_2100x2100-768x768.jpg 768w, https:\/\/hannainstruments.at\/wp-content\/uploads\/HI84500_2100x2100-1200x1200.jpg 1200w, https:\/\/hannainstruments.at\/wp-content\/uploads\/HI84500_2100x2100-300x300.jpg 300w, https:\/\/hannainstruments.at\/wp-content\/uploads\/HI84500_2100x2100-600x600.jpg 600w, https:\/\/hannainstruments.at\/wp-content\/uploads\/HI84500_2100x2100-100x100.jpg 100w\" alt=\"Schwefeldioxid-Mini-Titrator\" width=\"800\" height=\"800\" data-ll-status=\"loaded\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>Anwendungsbeispiel<\/h2>\n<p>Ein Kunde, der Wein herstellt, suchte nach einer M\u00f6glichkeit, den Schwefeldioxidgehalt zu messen. Sie verlangten, dass die Methode einfacher sein m\u00fcsse als das, was sie derzeit verwendeten, und dass sie kosteng\u00fcnstig sein m\u00fcsse, da sie ein kleiner Weinproduzent mit einem begrenzten Budget seien.\u00a0<a href=\"https:\/\/hannainstruments.at\/produkt\/sulfur-dioxide-mini-titrator-for-wine-hi84500-02-2\/\">Der Mini-Titrator HI84500 zur Messung von Schwefeldioxid in Wein<\/a>\u00a0ist das perfekte Werkzeug f\u00fcr jedes Weingut, ob gro\u00df oder klein, um Zeit zu sparen und den SO2-Titrationsprozess zu vereinfachen. Es ist wesentlich kosteng\u00fcnstiger als viele auf dem Markt erh\u00e4ltliche Titrationssysteme, da es sich auf einen einzigen Parameter, Schwefeldioxid, konzentriert. Der Kunde sch\u00e4tzte, dass das Verfahren leicht zu befolgen war und die Ergebnisse aufgrund der Kolbendosierung sehr genau und wiederholbar waren. Der Kunde war auch dankbar daf\u00fcr, dass die gelieferten Reagenzien vorgefertigt waren, so dass keine analytische Waage oder komplizierte Glasger\u00e4te erforderlich waren, um die f\u00fcr die Titration erforderlichen L\u00f6sungen herzustellen. Zu den weiteren wertvollen Merkmalen des Messger\u00e4ts geh\u00f6ren ein Punktmatrix-Display, mit dem der Verlauf der Titration grafisch dargestellt werden kann, USB-Anschl\u00fcsse f\u00fcr Flash-Laufwerk und PC-Konnektivit\u00e4t sowie eine dynamische Dosierung zur Beschleunigung der Titration und zur Vermeidung von \u00dcbertitration.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Beschreibung Schwefeldioxid (SO2) ist ein weit verbreiteter Zusatzstoff in der Weinindustrie, um Oxidation und bakteriellen [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":4490,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[568],"tags":[267],"class_list":["post-155141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-getranke","tag-wein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bestimmung von Schwefeldioxid in Wein - Hanna Instruments \u00d6sterreich<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bestimmung von Schwefeldioxid in Wein - Hanna Instruments \u00d6sterreich\" \/>\n<meta property=\"og:description\" content=\"Beschreibung Schwefeldioxid (SO2) ist ein weit verbreiteter Zusatzstoff in der Weinindustrie, um Oxidation und bakteriellen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/\" \/>\n<meta property=\"og:site_name\" content=\"Hanna Instruments \u00d6sterreich\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-30T11:31:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-11T08:12:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/03\/measuring-SO2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1015\" \/>\n\t<meta property=\"og:image:height\" content=\"594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Milan Petrovi\u0107\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Milan Petrovi\u0107\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/bestimmung-von-schwefeldioxid-in-wein\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/bestimmung-von-schwefeldioxid-in-wein\\\/\"},\"author\":{\"name\":\"Milan Petrovi\u0107\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/#\\\/schema\\\/person\\\/6872d7596a0a8c85e08ebf8440a39296\"},\"headline\":\"Bestimmung von Schwefeldioxid in Wein\",\"datePublished\":\"2020-06-30T11:31:15+00:00\",\"dateModified\":\"2022-10-11T08:12:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/bestimmung-von-schwefeldioxid-in-wein\\\/\"},\"wordCount\":379,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/bestimmung-von-schwefeldioxid-in-wein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/measuring-SO2.jpg\",\"keywords\":[\"Wein\"],\"articleSection\":[\"Getr\u00e4nke\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/bestimmung-von-schwefeldioxid-in-wein\\\/\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/bestimmung-von-schwefeldioxid-in-wein\\\/\",\"name\":\"Bestimmung von Schwefeldioxid in Wein - Hanna Instruments \u00d6sterreich\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/bestimmung-von-schwefeldioxid-in-wein\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/bestimmung-von-schwefeldioxid-in-wein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/measuring-SO2.jpg\",\"datePublished\":\"2020-06-30T11:31:15+00:00\",\"dateModified\":\"2022-10-11T08:12:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/bestimmung-von-schwefeldioxid-in-wein\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/bestimmung-von-schwefeldioxid-in-wein\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/bestimmung-von-schwefeldioxid-in-wein\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/measuring-SO2.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/measuring-SO2.jpg\",\"width\":1015,\"height\":594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/bestimmung-von-schwefeldioxid-in-wein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog home\",\"item\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bestimmung von Schwefeldioxid in Wein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/\",\"name\":\"Hanna Instruments Africa\",\"description\":\"pH-Meter, Photometer, Titratoren\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/#organization\",\"name\":\"Hanna Instruments\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/hs-logo.png\",\"contentUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/hs-logo.png\",\"width\":733,\"height\":225,\"caption\":\"Hanna Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/#\\\/schema\\\/person\\\/6872d7596a0a8c85e08ebf8440a39296\",\"name\":\"Milan Petrovi\u0107\",\"sameAs\":[\"http:\\\/\\\/blog.hannaservice.eu\"],\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/de\\\/author\\\/mpetrovic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bestimmung von Schwefeldioxid in Wein - Hanna Instruments \u00d6sterreich","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/","og_locale":"de_DE","og_type":"article","og_title":"Bestimmung von Schwefeldioxid in Wein - Hanna Instruments \u00d6sterreich","og_description":"Beschreibung Schwefeldioxid (SO2) ist ein weit verbreiteter Zusatzstoff in der Weinindustrie, um Oxidation und bakteriellen [&hellip;]","og_url":"https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/","og_site_name":"Hanna Instruments \u00d6sterreich","article_published_time":"2020-06-30T11:31:15+00:00","article_modified_time":"2022-10-11T08:12:18+00:00","og_image":[{"width":1015,"height":594,"url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/03\/measuring-SO2.jpg","type":"image\/jpeg"}],"author":"Milan Petrovi\u0107","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Milan Petrovi\u0107","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/#article","isPartOf":{"@id":"https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/"},"author":{"name":"Milan Petrovi\u0107","@id":"https:\/\/blog.hannaservice.eu\/de\/#\/schema\/person\/6872d7596a0a8c85e08ebf8440a39296"},"headline":"Bestimmung von Schwefeldioxid in Wein","datePublished":"2020-06-30T11:31:15+00:00","dateModified":"2022-10-11T08:12:18+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/"},"wordCount":379,"publisher":{"@id":"https:\/\/blog.hannaservice.eu\/de\/#organization"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/03\/measuring-SO2.jpg","keywords":["Wein"],"articleSection":["Getr\u00e4nke"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/","url":"https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/","name":"Bestimmung von Schwefeldioxid in Wein - Hanna Instruments \u00d6sterreich","isPartOf":{"@id":"https:\/\/blog.hannaservice.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/#primaryimage"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/03\/measuring-SO2.jpg","datePublished":"2020-06-30T11:31:15+00:00","dateModified":"2022-10-11T08:12:18+00:00","breadcrumb":{"@id":"https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/#primaryimage","url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/03\/measuring-SO2.jpg","contentUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/03\/measuring-SO2.jpg","width":1015,"height":594},{"@type":"BreadcrumbList","@id":"https:\/\/blog.hannaservice.eu\/de\/bestimmung-von-schwefeldioxid-in-wein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog home","item":"https:\/\/blog.hannaservice.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Bestimmung von Schwefeldioxid in Wein"}]},{"@type":"WebSite","@id":"https:\/\/blog.hannaservice.eu\/de\/#website","url":"https:\/\/blog.hannaservice.eu\/de\/","name":"Hanna Instruments Africa","description":"pH-Meter, Photometer, Titratoren","publisher":{"@id":"https:\/\/blog.hannaservice.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.hannaservice.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.hannaservice.eu\/de\/#organization","name":"Hanna Instruments","url":"https:\/\/blog.hannaservice.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.hannaservice.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/01\/hs-logo.png","contentUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/01\/hs-logo.png","width":733,"height":225,"caption":"Hanna Instruments"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.hannaservice.eu\/de\/#\/schema\/person\/6872d7596a0a8c85e08ebf8440a39296","name":"Milan Petrovi\u0107","sameAs":["https:\/\/blog.hannaservice.eu"],"url":"https:\/\/blog.hannaservice.eu\/de\/author\/mpetrovic\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.hannaservice.eu\/de\/wp-json\/wp\/v2\/posts\/155141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.hannaservice.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.hannaservice.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/de\/wp-json\/wp\/v2\/comments?post=155141"}],"version-history":[{"count":1,"href":"https:\/\/blog.hannaservice.eu\/de\/wp-json\/wp\/v2\/posts\/155141\/revisions"}],"predecessor-version":[{"id":155142,"href":"https:\/\/blog.hannaservice.eu\/de\/wp-json\/wp\/v2\/posts\/155141\/revisions\/155142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/de\/wp-json\/wp\/v2\/media\/4490"}],"wp:attachment":[{"href":"https:\/\/blog.hannaservice.eu\/de\/wp-json\/wp\/v2\/media?parent=155141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/de\/wp-json\/wp\/v2\/categories?post=155141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/de\/wp-json\/wp\/v2\/tags?post=155141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}