{"id":155448,"date":"2019-12-06T09:00:04","date_gmt":"2019-12-06T09:00:04","guid":{"rendered":"https:\/\/blog.hannaservice.eu\/mesurer-le-ph-du-fromage\/"},"modified":"2022-10-10T12:07:59","modified_gmt":"2022-10-10T12:07:59","slug":"mesurer-le-ph-du-fromage","status":"publish","type":"post","link":"https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/","title":{"rendered":"Mesurer le pH du fromage"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"155448\" class=\"elementor elementor-155448 elementor-43382\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-493fa01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"493fa01\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4426879\" data-id=\"4426879\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f701e5f elementor-widget elementor-widget-text-editor\" data-id=\"f701e5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>La mesure du pH pendant la fabrication du fromage est une \u00e9tape critique du contr\u00f4le qualit\u00e9 (CQ). Le pH offre une indication de la contamination par des bact\u00e9ries ou des produits chimiques tout en fournissant \u00e9galement une m\u00e9thode pratique pour estimer le d\u00e9veloppement acide d&rsquo;un produit laitier. Comme il existe une myriade de m\u00e9thodes d&rsquo;\u00e9chantillonnage, de directives d&rsquo;entretien des \u00e9lectrodes et de conceptions d&rsquo;\u00e9lectrodes diff\u00e9rentes, il peut \u00eatre difficile de d\u00e9terminer les meilleures pratiques pour mesurer le pH pendant la fabrication du fromage.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-209fd91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"209fd91\" data-element_type=\"section\" data-e-type=\"section\" id=\"postContent\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6365a93\" data-id=\"6365a93\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da88613 elementor-widget elementor-widget-text-editor\" data-id=\"da88613\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>Guide Rapide pour Mesurer le pH pendant la Fabrication du Fromage<\/h2>\n<p>La\u00a0production de fromage\u00a0\u00e7a commence par le m\u00e9tabolisme du lait par les cultures microbiennes. Ces cultures fermentent le lait, produisant de l\u2019acide lactique \u00e0 partir des sucres naturels. Ce processus de fermentation provoque une diminution du pH et permet aux saveurs de se d\u00e9velopper.<\/p>\n<p>Ensuite, le lait est s\u00e9par\u00e9 en composants solides et liquides gr\u00e2ce \u00e0 l\u2019utilisation de la pr\u00e9sure. Rennet est un complexe enzymatique qui est responsable du caillage des prot\u00e9ines dans le lait. Le composant solide qui en r\u00e9sulte est connu sous le nom de caill\u00e9, et le composant liquide est appel\u00e9 lactos\u00e9rum.<\/p>\n<p>Une fois que le lait est coagul\u00e9, le caill\u00e9 est ferment\u00e9 jusqu\u2019\u00e0 ce qu\u2019il atteigne un pH de 6,4. Il est ensuite s\u00e9par\u00e9 du lactos\u00e9rum et laiss\u00e9 pour former un tapis. \u00c0 ce stade, le tapis est coup\u00e9 en sections et superpos\u00e9 pour expulser plus de liquide.<\/p>\n<p>La fermentation se poursuit \u00e0 ce stade jusqu\u2019\u00e0 ce que le pH atteigne 5,1 \u00e0 5,5; puis le fromage est sal\u00e9 ou saumur\u00e9. Selon le style de fromage que vous fabriquez, un traitement suppl\u00e9mentaire peut \u00eatre effectu\u00e9 avant que le produit ne soit stock\u00e9, vieilli et emball\u00e9 pour \u00eatre distribu\u00e9.<\/p>\n<p>Tout au long du processus, il est essentiel de mesurer le pH pendant la fabrication du fromage afin d\u2019assurer une fermentation uniforme et la salubrit\u00e9 des aliments. Si le pH est trop bas, le fromage peut \u00eatre sujet \u00e0 une texture cassante ou p\u00e2teuse, ainsi qu\u2019\u00e0 la croissance de moisissure apr\u00e8s l\u2019emballage; si le pH est trop \u00e9lev\u00e9, le fromage peut devenir trop ferme et peut \u00eatre dangereux pour la consommation en raison du risque de formation d\u2019agents pathog\u00e8nes.<\/p>\n<h2>Mise en sc\u00e8ne du client<\/h2>\n<h3>D\u00e9fi<\/h3>\n<p>Une cr\u00e8merie locale a contact\u00e9 Hanna Instruments pour acqu\u00e9rir un pH m\u00e8tre qui faciliterait leur protocole de contr\u00f4le de la qualit\u00e9. Notre \u00e9quipe technique a recommand\u00e9 une \u00e9lectrode fournie avec l\u2019instrument \u00eatre r\u00e9sistant \u00e0 colmatage de la jonction, comme le client a d\u00e9j\u00e0 connu des lectures erratiques apr\u00e8s avoir pris des mesures dans des \u00e9mulsions visqueuses.<\/p>\n<h3>Recommandation<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0dbbcad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0dbbcad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5f6c6d5\" data-id=\"5f6c6d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d018f27 elementor-widget elementor-widget-text-editor\" data-id=\"d018f27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Hanna a\u00a0offert le pH m\u00e8tre portable\u00a0de fromage \u2013 HI99165 est un pH\/ C\u00b0 m\u00e8tre durable, \u00e9tanche et portable con\u00e7u sp\u00e9cifiquement pour l\u2019analyse du fromage.<\/p>\n<h4>\u00c9talonnage Facile<\/h4>\n<p>L\u2019\u00e9talonnage automatique est effectu\u00e9 en un ou deux points avec deux kits de solutions tampons. Toutes les lectures d\u2019\u00e9talonnage et de mesure sont automatiquement compens\u00e9es pour les variations de temp\u00e9rature.<\/p>\n<h4>Simple \u00e0 utiliser<\/h4>\n<p>L\u2019\u00e9cran LCD \u00e0 deux niveaux affiche \u00e0 la fois les lectures de pH et de temp\u00e9rature, ainsi que des indicateurs de stabilit\u00e9 de lecture, de pourcentage de batterie et d\u2019instructions d\u2019\u00e9talonnage.<\/p>\n<h4>\u00c9lectrode de pH sp\u00e9cialis\u00e9e<\/h4>\n<p>Le HI99165 utilise le corps en acier inoxydable FC242D, \u00e9lectrode de pH amplifi\u00e9e qui offre de nombreuses caract\u00e9ristiques qui am\u00e9liorent les tests de pH pour les producteurs de fromage.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b5d987c\" data-id=\"b5d987c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4df117f elementor-widget elementor-widget-image\" data-id=\"4df117f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2019\/12\/HI99165-Angle-2100x2100-1-600x600.jpg\" class=\"attachment-large size-large wp-image-151494\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2019\/12\/HI99165-Angle-2100x2100-1-600x600.jpg 600w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2019\/12\/HI99165-Angle-2100x2100-1-300x300.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2019\/12\/HI99165-Angle-2100x2100-1-150x150.jpg 150w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2019\/12\/HI99165-Angle-2100x2100-1-768x768.jpg 768w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2019\/12\/HI99165-Angle-2100x2100-1-1536x1536.jpg 1536w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2019\/12\/HI99165-Angle-2100x2100-1-2048x2048.jpg 2048w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La mesure du pH pendant la fabrication du fromage est une \u00e9tape critique du contr\u00f4le [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":4807,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[391],"tags":[291],"class_list":["post-155448","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aliments","tag-laiterie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mesurer le pH du fromage - Hanna Instruments Maroc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mesurer le pH du fromage - Hanna Instruments Maroc\" \/>\n<meta property=\"og:description\" content=\"La mesure du pH pendant la fabrication du fromage est une \u00e9tape critique du contr\u00f4le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/\" \/>\n<meta property=\"og:site_name\" content=\"Hanna Instruments Maroc\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-06T09:00:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-10T12:07:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/03\/CheeseWheels-500991-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"782\" \/>\n\t<meta property=\"og:image:height\" content=\"391\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Milan Petrovi\u0107\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Milan Petrovi\u0107\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesurer-le-ph-du-fromage\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesurer-le-ph-du-fromage\\\/\"},\"author\":{\"name\":\"Milan Petrovi\u0107\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/person\\\/6872d7596a0a8c85e08ebf8440a39296\"},\"headline\":\"Mesurer le pH du fromage\",\"datePublished\":\"2019-12-06T09:00:04+00:00\",\"dateModified\":\"2022-10-10T12:07:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesurer-le-ph-du-fromage\\\/\"},\"wordCount\":605,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesurer-le-ph-du-fromage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/CheeseWheels-500991-edited.jpg\",\"keywords\":[\"Laiterie\"],\"articleSection\":[\"Aliments\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesurer-le-ph-du-fromage\\\/\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesurer-le-ph-du-fromage\\\/\",\"name\":\"Mesurer le pH du fromage - Hanna Instruments Maroc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesurer-le-ph-du-fromage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesurer-le-ph-du-fromage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/CheeseWheels-500991-edited.jpg\",\"datePublished\":\"2019-12-06T09:00:04+00:00\",\"dateModified\":\"2022-10-10T12:07:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesurer-le-ph-du-fromage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesurer-le-ph-du-fromage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesurer-le-ph-du-fromage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/CheeseWheels-500991-edited.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/CheeseWheels-500991-edited.jpg\",\"width\":782,\"height\":391},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesurer-le-ph-du-fromage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog home\",\"item\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mesurer le pH du fromage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\",\"name\":\"Hanna Instruments Africa\",\"description\":\"pH M\u00e8tres, Photom\u00e8tres, Titrateurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\",\"name\":\"Hanna Instruments\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/hs-logo.png\",\"contentUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/hs-logo.png\",\"width\":733,\"height\":225,\"caption\":\"Hanna Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/person\\\/6872d7596a0a8c85e08ebf8440a39296\",\"name\":\"Milan Petrovi\u0107\",\"sameAs\":[\"http:\\\/\\\/blog.hannaservice.eu\"],\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/author\\\/mpetrovic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mesurer le pH du fromage - Hanna Instruments Maroc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/","og_locale":"fr_FR","og_type":"article","og_title":"Mesurer le pH du fromage - Hanna Instruments Maroc","og_description":"La mesure du pH pendant la fabrication du fromage est une \u00e9tape critique du contr\u00f4le [&hellip;]","og_url":"https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/","og_site_name":"Hanna Instruments Maroc","article_published_time":"2019-12-06T09:00:04+00:00","article_modified_time":"2022-10-10T12:07:59+00:00","og_image":[{"width":782,"height":391,"url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/03\/CheeseWheels-500991-edited.jpg","type":"image\/jpeg"}],"author":"Milan Petrovi\u0107","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Milan Petrovi\u0107","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/#article","isPartOf":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/"},"author":{"name":"Milan Petrovi\u0107","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/person\/6872d7596a0a8c85e08ebf8440a39296"},"headline":"Mesurer le pH du fromage","datePublished":"2019-12-06T09:00:04+00:00","dateModified":"2022-10-10T12:07:59+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/"},"wordCount":605,"publisher":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/03\/CheeseWheels-500991-edited.jpg","keywords":["Laiterie"],"articleSection":["Aliments"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/","url":"https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/","name":"Mesurer le pH du fromage - Hanna Instruments Maroc","isPartOf":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/#primaryimage"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/03\/CheeseWheels-500991-edited.jpg","datePublished":"2019-12-06T09:00:04+00:00","dateModified":"2022-10-10T12:07:59+00:00","breadcrumb":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/#primaryimage","url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/03\/CheeseWheels-500991-edited.jpg","contentUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/03\/CheeseWheels-500991-edited.jpg","width":782,"height":391},{"@type":"BreadcrumbList","@id":"https:\/\/blog.hannaservice.eu\/fr\/mesurer-le-ph-du-fromage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog home","item":"https:\/\/blog.hannaservice.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Mesurer le pH du fromage"}]},{"@type":"WebSite","@id":"https:\/\/blog.hannaservice.eu\/fr\/#website","url":"https:\/\/blog.hannaservice.eu\/fr\/","name":"Hanna Instruments Africa","description":"pH M\u00e8tres, Photom\u00e8tres, Titrateurs","publisher":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.hannaservice.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization","name":"Hanna Instruments","url":"https:\/\/blog.hannaservice.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/01\/hs-logo.png","contentUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/01\/hs-logo.png","width":733,"height":225,"caption":"Hanna Instruments"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/person\/6872d7596a0a8c85e08ebf8440a39296","name":"Milan Petrovi\u0107","sameAs":["https:\/\/blog.hannaservice.eu"],"url":"https:\/\/blog.hannaservice.eu\/fr\/author\/mpetrovic\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/155448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/comments?post=155448"}],"version-history":[{"count":1,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/155448\/revisions"}],"predecessor-version":[{"id":155449,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/155448\/revisions\/155449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/media\/4807"}],"wp:attachment":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/media?parent=155448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/categories?post=155448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/tags?post=155448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}