{"id":155508,"date":"2021-02-26T14:22:57","date_gmt":"2021-02-26T14:22:57","guid":{"rendered":"https:\/\/blog.hannaservice.eu\/mesure-du-ph\/"},"modified":"2022-10-10T10:51:52","modified_gmt":"2022-10-10T10:51:52","slug":"mesure-du-ph","status":"publish","type":"post","link":"https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/","title":{"rendered":"Mesure du pH"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"155508\" class=\"elementor elementor-155508 elementor-3037\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d60f82d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d60f82d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd5b8ed\" data-id=\"bd5b8ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90c495f elementor-widget elementor-widget-text-editor\" data-id=\"90c495f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Hanna Instruments propose des instruments \u00e0 param\u00e8tre unique et \u00e0 param\u00e8tres multiples afin de r\u00e9pondre \u00e0 une vari\u00e9t\u00e9 d&rsquo;exigences de test.<br \/>\nHanna Instruments propose des instruments \u00e0 param\u00e8tre unique et \u00e0 param\u00e8tres multiples afin de r\u00e9pondre \u00e0 une vari\u00e9t\u00e9 d&rsquo;exigences de test.<\/p>\n<p><strong>Utilisation d&rsquo;un seul param\u00e8tre<\/strong><br \/>\nLes instruments \u00e0 param\u00e8tre unique Hanna offrent une mesure simple, pr\u00e9cise et efficace ax\u00e9e sur, comme leur nom l&rsquo;indique, un param\u00e8tre unique. Ils sont bien adapt\u00e9s aux tests cibl\u00e9s o\u00f9 un param\u00e8tre doit \u00eatre test\u00e9 rapidement et facilement. Ils sont g\u00e9n\u00e9ralement simples \u00e0 utiliser et peuvent \u00eatre utilis\u00e9s par des utilisateurs non techniques.<\/p>\n<p><strong>Utilisation du multiparam\u00e8tre<\/strong><br \/>\nL&rsquo;avantage des instruments multiparam\u00e8tres Hanna est qu&rsquo;un utilisateur peut choisir un seul appareil de mesure avec la possibilit\u00e9 de mesurer plusieurs param\u00e8tres.<\/p>\n<p>Les instruments multiparam\u00e8tres offrent diff\u00e9rentes solutions d&rsquo;exploitation bien adapt\u00e9es pour r\u00e9pondre \u00e0 de multiples exigences et sont disponibles dans deux configurations principales :<\/p>\n<ol>\n<li>Compteurs multiparam\u00e8tres pouvant mesurer deux ou trois param\u00e8tres, mais un seul param\u00e8tre \u00e0 la fois.<\/li>\n<li>Compteurs multiparam\u00e8tres qui offrent deux ou trois param\u00e8tres mesur\u00e9s simultan\u00e9ment, utiles pour les applications exp\u00e9rimentales et de recherche o\u00f9 l&rsquo;influence entre les param\u00e8tres est un facteur important. Les entr\u00e9es multiples permettent une mesure simultan\u00e9e.<\/li>\n<\/ol>\n<p><strong>Entr\u00e9e de mesure de pH<\/strong><br \/>\nLes compteurs Hanna sont g\u00e9n\u00e9ralement disponibles en deux types de connexion d&rsquo;\u00e9lectrodes diff\u00e9rents : BNC ou DIN.<\/p>\n<p>Connecteur BNC : Un BNC (Bayonet Neil-Concelman) est un connecteur commun utilis\u00e9 pour les appareils \u00e0 c\u00e2ble coaxial. Une connexion BNC est g\u00e9n\u00e9ralement utilis\u00e9e pour les \u00e9lectrodes combin\u00e9es et les \u00e9lectrodes \u00e0 demi-cellule qui n\u00e9cessitent une sonde de r\u00e9f\u00e9rence s\u00e9par\u00e9e et une entr\u00e9e de r\u00e9f\u00e9rence s\u00e9par\u00e9e.<\/p>\n<p>Connecteur DIN : Un DIN (Deutches Institut f\u00fcr Normung) est un connecteur circulaire. Il est utilis\u00e9 pour connecter des \u00e9lectrodes de mesure de pH amplifi\u00e9es. Les \u00e9lectrodes utilisant un connecteur DIN comportent un capteur de temp\u00e9rature int\u00e9gr\u00e9.<\/p>\n<p><strong>Entr\u00e9e de temp\u00e9rature<\/strong><br \/>\nLa temp\u00e9rature a un effet sur les mesures de pH. En tant que telle, la compensation de temp\u00e9rature est requise pour des mesures pr\u00e9cises. La compensation de temp\u00e9rature peut \u00eatre obtenue de trois mani\u00e8res\u00a0:<\/p>\n<ol>\n<li>Une sonde s\u00e9par\u00e9e sp\u00e9cifiquement pour mesurer la temp\u00e9rature<\/li>\n<li>Une sonde avec un capteur de temp\u00e9rature int\u00e9gr\u00e9.<\/li>\n<li>R\u00e9glage manuel de la temp\u00e9rature<\/li>\n<\/ol>\n<p>Si une entr\u00e9e de temp\u00e9rature n&rsquo;est pas pr\u00e9sente, de nombreux instruments offrent toujours la possibilit\u00e9 d&rsquo;ajuster manuellement la temp\u00e9rature en fonction d&rsquo;une r\u00e9f\u00e9rence de temp\u00e9rature externe.<\/p>\n<p><strong>Mesure de pH Compensation de temp\u00e9rature<\/strong><br \/>\nLes lectures de pH doivent \u00eatre compens\u00e9es en temp\u00e9rature afin d&rsquo;obtenir des r\u00e9sultats pr\u00e9cis. La source de mesure de la temp\u00e9rature peut provenir d&rsquo;un capteur de temp\u00e9rature ou d&rsquo;un trimmer qui est ajust\u00e9 manuellement. Dans les deux cas, l&rsquo;instrument ajuste la lecture du pH pour compenser les changements dans le Capteur de pH. La compensation en pH fournit le pH r\u00e9el \u00e0 la temp\u00e9rature de mesure.<\/p>\n<p><strong>Lecture en mV<\/strong><br \/>\nLes compteurs Hanna dot\u00e9s d&rsquo;une fonction mV offrent la possibilit\u00e9 de lire le potentiel mV \u00e0 partir d&rsquo;une \u00e9lectrode pH, ORP ou ISE. Le mV relatif permet \u00e0 l&rsquo;utilisateur de compenser la diff\u00e9rence mV g\u00e9n\u00e9r\u00e9e \u00e0 partir de capteurs ou de r\u00e9f\u00e9rences.<\/p>\n<p><strong>\u00c9talonnage pH\/ISE<\/strong><br \/>\nL&rsquo;\u00e9talonnage du pH doit \u00eatre effectu\u00e9 quotidiennement ou \u00e0 chaque fois qu&rsquo;un nouveau lot de lectures est d\u00e9marr\u00e9. Toute erreur pendant l&rsquo;\u00e9talonnage affectera toutes les lectures jusqu&rsquo;\u00e0 ce qu&rsquo;un nouvel \u00e9talonnage soit effectu\u00e9.<\/p>\n<p>Hanna recommande la proc\u00e9dure d&rsquo;\u00e9talonnage standard suivante\u00a0:<\/p>\n<ul>\n<li>Nettoyer et activer l&rsquo;\u00e9lectrode avant l&rsquo;\u00e9talonnage.<\/li>\n<li>Utilisez des tampons et des \u00e9talons de pH frais.<\/li>\n<li>Rincer l&rsquo;\u00e9lectrode avec de l&rsquo;eau purifi\u00e9e pendant le processus d&rsquo;\u00e9talonnage pour \u00e9viter la contamination du tampon, puis un rin\u00e7age dans le tampon ou l&rsquo;\u00e9talon.<\/li>\n<li>Attendez une lecture stable avant que le point d&rsquo;\u00e9talonnage soit confirm\u00e9.<\/li>\n<li>Compensation de temp\u00e9rature de la lecture du pH et des tampons de pH.<\/li>\n<\/ul>\n<p>L&rsquo;\u00e9talonnage est un \u00e9l\u00e9ment cl\u00e9 pour garantir des lectures pr\u00e9cises lors de la mesure du pH. Dans cet esprit, Hanna fournit \u00e0 chacun de nos instruments de pH un ensemble de solutions d&rsquo;\u00e9talonnage de d\u00e9marrage.<\/p>\n<h3>pH CAL Check\u2122<\/h3>\n<p>De nombreux instruments sont dot\u00e9s de la technologie exclusive pH CAL Check de Hanna. CAL Check est un syst\u00e8me de diagnostic qui garantit des lectures de pH pr\u00e9cises \u00e0 chaque fois. En alertant les utilisateurs des probl\u00e8mes potentiels pendant le processus d&rsquo;\u00e9talonnage, le syst\u00e8me CAL Check \u00e9limine les lectures erron\u00e9es dues \u00e0 des \u00e9lectrodes de pH sales ou d\u00e9fectueuses ou solutions tampons pH contamin\u00e9es pendant l&rsquo;\u00e9talonnage.<\/p>\n<p>Pendant le processus d&rsquo;\u00e9talonnage, les utilisateurs sont invit\u00e9s \u00e0 suivre un didacticiel \u00e9tape par \u00e9tape \u00e0 l&rsquo;\u00e9cran. Apr\u00e8s l&rsquo;\u00e9talonnage, l&rsquo;\u00e9lectrode est \u00e9valu\u00e9e et l&rsquo;\u00e9tat et le temps de r\u00e9ponse sont fournis. Selon le compteur, il peut s&rsquo;agir d&rsquo;un graphique des informations BPL.<\/p>\n<p><strong>Erreurs d&rsquo;\u00e9talonnage<\/strong><br \/>\nLes instruments utilisant la technologie CAL Check de Hanna peuvent \u00e9valuer une \u00e9lectrode pendant l&rsquo;\u00e9talonnage et stocker un historique des param\u00e8tres qui d\u00e9crivent la qualit\u00e9 de l&rsquo;\u00e9lectrode \u00e0 comparer d&rsquo;un \u00e9talonnage \u00e0 l&rsquo;autre. Pendant l&rsquo;\u00e9talonnage, une tr\u00e8s faible d\u00e9gradation de ces param\u00e8tres est normale et peut \u00eatre attendue. Un grand changement dans les param\u00e8tres signifie une erreur dans la proc\u00e9dure d&rsquo;\u00e9talonnage, comme une \u00e9lectrode sale.<\/p>\n<p><strong>Contamination du tampon pH<\/strong><br \/>\nLes tampons de pH peuvent \u00eatre contamin\u00e9s pendant la proc\u00e9dure d&rsquo;\u00e9talonnage par de nombreux facteurs tels que l&rsquo;introduction d&rsquo;une sonde contamin\u00e9e, l&rsquo;utilisation d&rsquo;anciens tampons ou la r\u00e9utilisation de tampons. Ces facteurs peuvent entra\u00eener un \u00e9talonnage et des mesures ult\u00e9rieures inexacts.<\/p>\n<p>Le contr\u00f4le CAL de Hanna peut souvent d\u00e9tecter des probl\u00e8mes pendant l&rsquo;\u00e9talonnage, en donnant des messages d&rsquo;avertissement pour informer les utilisateurs du probl\u00e8me identifi\u00e9.<\/p>\n<p><strong>Temps de r\u00e9ponse des \u00e9lectrodes<\/strong><br \/>\nUn autre param\u00e8tre qui est \u00e9valu\u00e9 lors de l&rsquo;\u00e9talonnage avec certains compteurs dot\u00e9s de la technologie CAL Check est le temps de r\u00e9ponse d&rsquo;une \u00e9lectrode. Celui-ci est \u00e9valu\u00e9 en fonction du temps n\u00e9cessaire pour atteindre la stabilit\u00e9 lorsque l&rsquo;\u00e9lectrode est immerg\u00e9e dans un nouveau tampon qui pr\u00e9sente une diff\u00e9rence. en pH sup\u00e9rieur \u00e0 3 unit\u00e9s de pH par rapport \u00e0 l&rsquo;ancien.<\/p>\n<p><strong>D\u00e9calage et pente de l&rsquo;\u00e9lectrode de pH<\/strong><br \/>\nL&rsquo;offset et la pente sont les param\u00e8tres les plus importants qui peuvent d\u00e9crire la qualit\u00e9 d&rsquo;une \u00e9lectrode. Avec la technologie CAL Check de Hanna, l&rsquo;offset de l&rsquo;\u00e9lectrode peut \u00eatre \u00e9valu\u00e9 \u00e0 l&rsquo;aide d&rsquo;un \u00e9talonnage en un point. L&rsquo;offset est g\u00e9n\u00e9ralement d\u00e9termin\u00e9 \u00e0 l&rsquo;aide d&rsquo;un tampon pH 7,01, cependant, en utilisant CAL Check permet au d\u00e9calage d&rsquo;\u00eatre bas\u00e9 sur n&rsquo;importe quel point d&rsquo;\u00e9talonnage. La plage acceptable pour le d\u00e9calage est de \u00b130 mV bien qu&rsquo;un avertissement puisse s&rsquo;afficher.<\/p>\n<p>Un minimum de deux points d&rsquo;\u00e9talonnage est n\u00e9cessaire pour d\u00e9terminer la pente. La pente peut \u00eatre \u00e9valu\u00e9e entre deux points d&rsquo;\u00e9talonnage et doit normalement se situer dans une plage de 92 % \u00e0 110 %, o\u00f9 100 % correspond \u00e0 59,16 mV\/pH \u00e0 25 \u00b0C.<\/p>\n<p><strong>Points d&rsquo;\u00e9talonnage et tampons pH<\/strong><br \/>\nL&rsquo;\u00e9talonnage d&rsquo;une \u00e9lectrode de pH est normalement effectu\u00e9 en utilisant deux points\u00a0: 7 pH et 4 ou 10 pH. Ceci est bas\u00e9 sur l&rsquo;hypoth\u00e8se que l&rsquo;\u00e9lectrode de pH est lin\u00e9aire de 3 pH \u00e0 10 pH. Pour la lecture la plus pr\u00e9cise, Hanna recommande en utilisant un point d&rsquo;\u00e9talonnage le plus proche des valeurs re\u00e7ues lors d&rsquo;une mesure normale.<\/p>\n<p>Pour une vari\u00e9t\u00e9 d&rsquo;applications et de points de mesure, de nombreux appareils de mesure Hanna offrent la possibilit\u00e9 d&rsquo;\u00e9talonner en utilisant plus de deux points. De nombreux instruments Hanna offrent 2, 3 ou jusqu&rsquo;\u00e0 5 points d&rsquo;\u00e9talonnage pour une pr\u00e9cision am\u00e9lior\u00e9e. Tampons pH 1,68, 3,00, 4,01, 6,86 , 7.01, 9.18, 10.01 et 12.45 couvrent toute la plage de pH.<\/p>\n<p>Pendant l&rsquo;\u00e9talonnage, les tampons de pH reconnus sont compens\u00e9s en temp\u00e9rature par l&rsquo;instrument afin de tenir compte de la variation de pH des tampons due \u00e0 la temp\u00e9rature. Par exemple, un tampon de pH 10,01 est un pH de 10,01 uniquement @ 25\u00b0CA un tableau de variation de temp\u00e9rature est imprim\u00e9 sur l&rsquo;\u00e9tiquette de chaque tampon pH.<\/p>\n<p><strong>Tampons de pH personnalis\u00e9s<\/strong><br \/>\nHanna a impl\u00e9ment\u00e9 le concept de tampons pH personnalis\u00e9s dans plusieurs de ses instruments. Cela permet \u00e0 l&rsquo;utilisateur d&rsquo;ajouter un tampon sp\u00e9cifique \u00e0 l&rsquo;industrie pour l&rsquo;\u00e9talonnage. Cependant, la compensation de temp\u00e9rature pendant l&rsquo;\u00e9talonnage n&rsquo;est pas impl\u00e9ment\u00e9e car la corr\u00e9lation de variation de temp\u00e9rature est inconnue.<\/p>\n<p><strong>Stabilit\u00e9 pendant l&rsquo;\u00e9talonnage<\/strong><br \/>\nLa stabilit\u00e9 des lectures est importante afin d&rsquo;\u00e9viter un \u00e9talonnage incorrect. Sur cette base, la confirmation d&rsquo;un nouveau point d&rsquo;\u00e9talonnage n&rsquo;est effectu\u00e9e qu&rsquo;une fois la stabilit\u00e9 atteinte. Les utilisateurs sont inform\u00e9s pendant tous les processus des conditions de stabilit\u00e9, et toute instabilit\u00e9 relancera la stabilit\u00e9 \u00e9valuation.Le crit\u00e8re de stabilit\u00e9 lors de l&rsquo;\u00e9talonnage est plus rigoureux que lors de la mesure.Ce mode utilis\u00e9 dans l&rsquo;instrumentation Hanna \u00e9vite les erreurs par confirmation des points d&rsquo;\u00e9talonnage lors de lectures instables.Ce principe est respect\u00e9 dans tout type d&rsquo;\u00e9talonnage, manuel ou automatique.<\/p>\n<p><strong>Hors de la plage d&rsquo;\u00e9talonnage<\/strong><br \/>\nIl s&rsquo;agit d&rsquo;une caract\u00e9ristique importante pendant la mesure et est consid\u00e9r\u00e9e comme une bonne pratique de laboratoire (BPL). La mesure est consid\u00e9r\u00e9e comme plus pr\u00e9cise. Si la lecture de la mesure se situe dans une plage \u00e9loign\u00e9e des points d&rsquo;\u00e9talonnage, le message \u00ab\u00a0hors plage d&rsquo;\u00e9talonnage\u00a0\u00bb s&rsquo;affiche. la valeur mesur\u00e9e est affich\u00e9e et l&rsquo;utilisateur peut l&rsquo;accepter, mais avec l&rsquo;avertissement de l&rsquo;instrument li\u00e9 \u00e0 une \u00e9ventuelle impr\u00e9cision.<\/p>\n<p><strong>Rappel d&rsquo;\u00e9talonnage<\/strong><br \/>\nLe rappel d&rsquo;\u00e9talonnage, comme \u00ab\u00a0hors de la plage d&rsquo;\u00e9talonnage\u00a0\u00bb, est un message d&rsquo;avertissement BPL. Des \u00e9talonnages r\u00e9guliers sont essentiels pour des mesures pr\u00e9cises et reproductibles. Un rappel d&rsquo;avertissement s&rsquo;affiche lorsque le capteur a besoin d&rsquo;un \u00e9talonnage. Les mesures peuvent toujours \u00eatre utilis\u00e9es sous le rappel d&rsquo;avertissement .<\/p>\n<p><strong>\u00c9talonnage \u00e9tape par \u00e9tape<\/strong><br \/>\nAfin d&rsquo;\u00e9viter les erreurs lors de la proc\u00e9dure d&rsquo;\u00e9talonnage, les compteurs affichent des indicateurs qui peuvent \u00eatre suivis par l&rsquo;utilisateur pour un \u00e9talonnage r\u00e9ussi. Si n\u00e9cessaire, il est possible que les \u00e9tapes d&rsquo;\u00e9talonnage soient effectu\u00e9es dans un ordre diff\u00e9rent par l&rsquo;utilisateur.<\/p>\n<p><strong>Caract\u00e9ristiques suppl\u00e9mentaires<\/strong><br \/>\nLes normes BPL et ISO exigent la tra\u00e7abilit\u00e9 des op\u00e9rations. Les BPL de Hanna documentent la qualit\u00e9 de l&rsquo;\u00e9talonnage, ainsi que des informations permettant d&rsquo;identifier l&rsquo;instrument, l&rsquo;op\u00e9rateur et l&rsquo;heure \u00e0 laquelle l&rsquo;\u00e9talonnage a \u00e9t\u00e9 effectu\u00e9.<\/p>\n<p>L&rsquo;enregistrement est une caract\u00e9ristique commune \u00e0 de nombreux instruments et peut \u00eatre utilis\u00e9 pour enregistrer des lectures. Deux modes de travail sont disponibles\u00a0: enregistrement \u00e0 la demande et enregistrement automatique ou \u00e0 intervalles. Avec l&rsquo;enregistrement \u00e0 la demande, les mesures consid\u00e9r\u00e9es comme importantes peuvent \u00eatre enregistr\u00e9es avec le Appuyez sur le bouton d&rsquo;enregistrement. Avec l&rsquo;enregistrement automatique ou \u00e0 intervalles, l&rsquo;instrument enregistre toutes les lectures selon un intervalle sp\u00e9cifi\u00e9. Un autre mode d&rsquo;enregistrement est l&rsquo;enregistrement de fin automatique ou la stabilit\u00e9 de l&rsquo;enregistrement.<\/p>\n<p>De nombreux compteurs Hanna incluent des \u00e9crans LCD graphiques avec des fonctionnalit\u00e9s telles que des didacticiels, une aide contextuelle, une prise en charge multilingue et des ic\u00f4nes et des messages pour guider l&rsquo;utilisateur tout au long du fonctionnement et de l&rsquo;\u00e9talonnage.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Hanna Instruments propose des instruments \u00e0 param\u00e8tre unique et \u00e0 param\u00e8tres multiples afin de r\u00e9pondre [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":2813,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[398],"tags":[299],"class_list":["post-155508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-laboratoire","tag-parameters-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mesure du pH - Hanna Instruments Maroc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mesure du pH - Hanna Instruments Maroc\" \/>\n<meta property=\"og:description\" content=\"Hanna Instruments propose des instruments \u00e0 param\u00e8tre unique et \u00e0 param\u00e8tres multiples afin de r\u00e9pondre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/\" \/>\n<meta property=\"og:site_name\" content=\"Hanna Instruments Maroc\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-26T14:22:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-10T10:51:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/02\/grafika2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Milan Petrovi\u0107\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Milan Petrovi\u0107\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesure-du-ph\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesure-du-ph\\\/\"},\"author\":{\"name\":\"Milan Petrovi\u0107\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/person\\\/6872d7596a0a8c85e08ebf8440a39296\"},\"headline\":\"Mesure du pH\",\"datePublished\":\"2021-02-26T14:22:57+00:00\",\"dateModified\":\"2022-10-10T10:51:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesure-du-ph\\\/\"},\"wordCount\":2011,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesure-du-ph\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/grafika2.jpg\",\"keywords\":[\"Parameters\"],\"articleSection\":[\"Laboratoire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesure-du-ph\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesure-du-ph\\\/\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesure-du-ph\\\/\",\"name\":\"Mesure du pH - Hanna Instruments Maroc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesure-du-ph\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesure-du-ph\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/grafika2.jpg\",\"datePublished\":\"2021-02-26T14:22:57+00:00\",\"dateModified\":\"2022-10-10T10:51:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesure-du-ph\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesure-du-ph\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesure-du-ph\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/grafika2.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/grafika2.jpg\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/mesure-du-ph\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog home\",\"item\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mesure du pH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\",\"name\":\"Hanna Instruments Africa\",\"description\":\"pH M\u00e8tres, Photom\u00e8tres, Titrateurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\",\"name\":\"Hanna Instruments\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/hs-logo.png\",\"contentUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/hs-logo.png\",\"width\":733,\"height\":225,\"caption\":\"Hanna Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/person\\\/6872d7596a0a8c85e08ebf8440a39296\",\"name\":\"Milan Petrovi\u0107\",\"sameAs\":[\"http:\\\/\\\/blog.hannaservice.eu\"],\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/author\\\/mpetrovic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mesure du pH - Hanna Instruments Maroc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/","og_locale":"fr_FR","og_type":"article","og_title":"Mesure du pH - Hanna Instruments Maroc","og_description":"Hanna Instruments propose des instruments \u00e0 param\u00e8tre unique et \u00e0 param\u00e8tres multiples afin de r\u00e9pondre [&hellip;]","og_url":"https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/","og_site_name":"Hanna Instruments Maroc","article_published_time":"2021-02-26T14:22:57+00:00","article_modified_time":"2022-10-10T10:51:52+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/02\/grafika2.jpg","type":"image\/jpeg"}],"author":"Milan Petrovi\u0107","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Milan Petrovi\u0107","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/#article","isPartOf":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/"},"author":{"name":"Milan Petrovi\u0107","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/person\/6872d7596a0a8c85e08ebf8440a39296"},"headline":"Mesure du pH","datePublished":"2021-02-26T14:22:57+00:00","dateModified":"2022-10-10T10:51:52+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/"},"wordCount":2011,"commentCount":0,"publisher":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/02\/grafika2.jpg","keywords":["Parameters"],"articleSection":["Laboratoire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/","url":"https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/","name":"Mesure du pH - Hanna Instruments Maroc","isPartOf":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/#primaryimage"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/02\/grafika2.jpg","datePublished":"2021-02-26T14:22:57+00:00","dateModified":"2022-10-10T10:51:52+00:00","breadcrumb":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/#primaryimage","url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/02\/grafika2.jpg","contentUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/02\/grafika2.jpg","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/blog.hannaservice.eu\/fr\/mesure-du-ph\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog home","item":"https:\/\/blog.hannaservice.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Mesure du pH"}]},{"@type":"WebSite","@id":"https:\/\/blog.hannaservice.eu\/fr\/#website","url":"https:\/\/blog.hannaservice.eu\/fr\/","name":"Hanna Instruments Africa","description":"pH M\u00e8tres, Photom\u00e8tres, Titrateurs","publisher":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.hannaservice.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization","name":"Hanna Instruments","url":"https:\/\/blog.hannaservice.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/01\/hs-logo.png","contentUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/01\/hs-logo.png","width":733,"height":225,"caption":"Hanna Instruments"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/person\/6872d7596a0a8c85e08ebf8440a39296","name":"Milan Petrovi\u0107","sameAs":["https:\/\/blog.hannaservice.eu"],"url":"https:\/\/blog.hannaservice.eu\/fr\/author\/mpetrovic\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/155508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/comments?post=155508"}],"version-history":[{"count":1,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/155508\/revisions"}],"predecessor-version":[{"id":155509,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/155508\/revisions\/155509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/media\/2813"}],"wp:attachment":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/media?parent=155508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/categories?post=155508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/tags?post=155508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}