{"id":157918,"date":"2022-01-26T15:15:03","date_gmt":"2022-01-26T15:15:03","guid":{"rendered":"https:\/\/blog.hannaservice.eu\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/"},"modified":"2022-10-10T10:43:30","modified_gmt":"2022-10-10T10:43:30","slug":"comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine","status":"publish","type":"post","link":"https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/","title":{"rendered":"Comment pr\u00e9parer sa piscine pour la nouvelle saison ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"157918\" class=\"elementor elementor-157918 elementor-157363\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9c66d4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9c66d4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d7375e\" data-id=\"5d7375e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d34bf02 elementor-widget elementor-widget-image\" data-id=\"d34bf02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"349\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/pool1-600x349.jpg\" class=\"attachment-large size-large wp-image-157383\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/pool1-600x349.jpg 600w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/pool1-300x175.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/pool1.jpg 624w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15810a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15810a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-286243a\" data-id=\"286243a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9f4a5e elementor-widget elementor-widget-text-editor\" data-id=\"c9f4a5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Il n&rsquo;est jamais trop t\u00f4t (ni trop tard) pour suivre l&rsquo;entretien de votre piscine.<\/p>\n<p>Vous vous voyez maintenant allong\u00e9 \u00e0 c\u00f4t\u00e9 de la piscine cristalline avec un cocktail dans les mains ? Pas de probl\u00e8me, vous pouvez facilement y \u00eatre apr\u00e8s quelques \u00e9tapes faciles :<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-317d90d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"317d90d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a37dcd\" data-id=\"0a37dcd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1cd7f04 elementor-widget elementor-widget-accordion\" data-id=\"1cd7f04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3021\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-3021\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00c9tape principale - Nettoyer physiquement votre piscine (nous voulons dire physiquement)<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3021\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-3021\"><p>Le premier et le plus \u00e9vident est de prendre soin des gros d\u00e9bris et des feuilles. L&rsquo;accent est mis sur tout ce qui est gros et volumineux susceptible d&rsquo;obstruer le filtre de la piscine.<\/p>\n<p>L&rsquo;\u00e9tape suivante et la plus importante consiste \u00e0 nettoyer \u00e9galement les filtres. Cela doit \u00eatre facile, nettoyez les d\u00e9p\u00f4ts \u00e9ventuels avec une brosse et proc\u00e9dez \u00e0 un nettoyage r\u00e9gulier \u00e0 l&rsquo;eau. <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3022\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-3022\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Secondaire \u2013 Traitement chimique <\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3022\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-3022\"><p>\u00c0 ce stade, il est temps de remplir la piscine d&rsquo;eau et de d\u00e9marrer l&rsquo;\u00e9quipement de la piscine, le filtre et la pompe.<\/p>\n<p>Le traitement chimique recommand\u00e9 est <strong>hyper chloration\/choc<\/strong><\/p>\n<p>Les agents \u00e0 base de chlore sont les plus couramment utilis\u00e9s pour d\u00e9sinfecter l&rsquo;eau de la piscine. Quel que soit le chlore en question, il est n\u00e9cessaire de surveiller le niveau de ce que l&rsquo;on appelle le chlore libre, qui dans l&rsquo;eau de la piscine doit avoir une concentration allant jusqu&rsquo;\u00e0 1,02 mg\/l.<\/p>\n<p>Pour bien doser les agents d&rsquo;entretien et de chloration de la piscine, il faut savoir combien de m\u00e8tres cubes d&rsquo;eau contiendront la piscine.<\/p>\n<p>L\u2019hyper chloration de l&rsquo;eau de la piscine est r\u00e9alis\u00e9e dans le but de nettoyer la piscine. L&rsquo;eau hyper chlor\u00e9e doit \u00eatre laiss\u00e9e dans la piscine pendant au moins 24 heures pour d\u00e9sinfecter les parois de la piscine. Apr\u00e8s cela, l&rsquo;eau doit \u00eatre \u00e9vacu\u00e9e de la piscine, la piscine doit \u00eatre remplie d&rsquo;eau douce et une chloration continue doit \u00eatre effectu\u00e9e. L&rsquo;eau hyperchlor\u00e9e ne doit pas \u00eatre utilis\u00e9e pour le bain car elle contient trop de chlore.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3023\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-3023\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Bilan hydrique \u2013 mesure\/surveillance<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-3023\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-3023\"><p>Il est recommand\u00e9 de laisser la piscine se stabiliser pendant 24 \u00e0 48 heures, puis de tester les niveaux chimiques de votre eau pour pr\u00e9parer votre piscine \u00e0 la baignade.<\/p>\n<p>De nombreux \u00e9quipements sont disponibles pour v\u00e9rifier que tous vos niveaux se situent dans la plage recommand\u00e9e :<\/p>\n<ul>\n<li><span style=\"text-decoration: underline;\"><strong>pH:<\/strong><\/span> 4 \u2013 7.6. Le pH est le param\u00e8tre le plus important car il affecte directement<\/li>\n<\/ul>\n<p>le pouvoir du chlore.<\/p>\n<p>Trop faible : <em>Augmenter<\/em>ajouter du bicarbonate de sodium<\/p>\n<p>Trop \u00e9lev\u00e9 : <em>Diminuer<\/em> <em>\u00e0<\/em> <em> <\/em>ajouter du bisulfate de sodium\/acide chlorhydrique<\/p>\n<ul>\n<li><span style=\"text-decoration: underline;\"><strong>R\u00e9dox<\/strong><\/span> \u2013 650 mV \u00e0 750 mV<\/li>\n<\/ul>\n<p>Trop faible \u2013 Augmenter <em>\u00e0<\/em><strong>ajouter<\/strong> du chlore<\/p>\n<p>Trop \u00e9lev\u00e9 &#8211; peu susceptible de se produire<\/p>\n<ul>\n<li><span style=\"text-decoration: underline;\"><strong>Chlore<\/strong><\/span>: 1.00 \u2013 3.00 ppm<\/li>\n<\/ul>\n<p>Trop faible &#8211; Augmenter : ajouter du <strong>chlore<\/strong><\/p>\n<p>Trop \u00e9lev\u00e9e* <em>Diminution<\/em><em>\u00e0<\/em> <em> <\/em>Thiosulfate de sodium \/ peroxyde d&rsquo;hydrog\u00e8ne<\/p>\n<p>*Au d\u00e9but, des niveaux plus \u00e9lev\u00e9s possibles en raison de l&rsquo;hyperchloration<\/p>\n<ul>\n<li><span style=\"text-decoration: underline;\"><strong>Temp\u00e9rature <\/strong><\/span>&#8211; En r\u00e8gle g\u00e9n\u00e9rale, pour chaque augmentation de 5,5 \u00b0C de la temp\u00e9rature de l&rsquo;eau au-del\u00e0 de 27 \u00b0C, la concentration de d\u00e9sinfectant requise est doubl\u00e9e.<\/li>\n<li><span style=\"text-decoration: underline;\"><strong>Alcalinit\u00e9<\/strong><\/span> (stabilise le niveau de pH) : 80 \u2013 140 ppm.<\/li>\n<\/ul>\n<p>Trop bas : <em>Augmenter<\/em><em>\u00e0<\/em> ajouter du bicarbonate de sodium<\/p>\n<p>Trop \u00e9lev\u00e9 : <em>Diminuer<\/em> <em>\u00e0<\/em> <em> <\/em>ajouter du bisulfate de sodium\/acide chlorhydrique<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9aa3fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9aa3fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ef8d3b3\" data-id=\"ef8d3b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d92fe51 elementor-widget elementor-widget-image\" data-id=\"d92fe51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"600\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/pool2-400x600.jpg\" class=\"attachment-large size-large wp-image-157389\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/pool2-400x600.jpg 400w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/pool2-200x300.jpg 200w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/pool2-768x1152.jpg 768w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/pool2.jpg 1000w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-46b432e\" data-id=\"46b432e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1efca49 elementor-widget elementor-widget-heading\" data-id=\"1efca49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lorsque vous \u00e9quilibrez l'eau, rendez-la limpide, votre piscine est pr\u00eate \u00e0 \u00eatre appr\u00e9ci\u00e9e.<br> Vous pouvez maintenant sortir les transats et apporter des lunettes de soleil !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f6127ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f6127ff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-821420c\" data-id=\"821420c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b179178 elementor-widget elementor-widget-text-editor\" data-id=\"b179178\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Sans traitement appropri\u00e9, l&rsquo;eau de la piscine peut facilement devenir insalubre ; les algues, les bact\u00e9ries et autres micro-organismes peuvent se d\u00e9velopper dans l&rsquo;eau.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73c93a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73c93a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-606659b\" data-id=\"606659b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8f8d57 elementor-widget elementor-widget-text-editor\" data-id=\"a8f8d57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Il existe \u00e9galement un danger li\u00e9 \u00e0 l&rsquo;accumulation de min\u00e9raux, qui peut causer de graves dommages \u00e0 la tuyauterie interne ou provoquer le tartre sur les murs et la coque.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22e9295 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22e9295\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40facfa\" data-id=\"40facfa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dba6197 elementor-widget elementor-widget-text-editor\" data-id=\"dba6197\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>La technologie peut garder l&rsquo;eau de votre piscine fra\u00eeche et propre et emp\u00eacher l&rsquo;eau de la piscine de devenir potentiellement nocive. Il existe une vari\u00e9t\u00e9 de syst\u00e8mes de traitement de l&rsquo;eau efficaces disponibles qui peuvent donner des r\u00e9sultats tr\u00e8s positifs avec un entretien appropri\u00e9.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e1aa48a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e1aa48a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-471e6f9\" data-id=\"471e6f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2e10ee elementor-widget elementor-widget-text-editor\" data-id=\"d2e10ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Les syst\u00e8mes de d\u00e9sinfection au chlore en ligne distribuent automatiquement le chlore dans l&rsquo;eau de la piscine. Cela maintient une quantit\u00e9 <span style=\"text-decoration: underline;\"><strong>r\u00e9siduelle constante de chlore<\/strong><\/span>, ce qui emp\u00eache la croissance bact\u00e9rienne et \u00e9limine les contaminants. Les min\u00e9raux inhibent la croissance des bact\u00e9ries et adoucissent la sensation de l&rsquo;eau.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad89b2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad89b2a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b8d339\" data-id=\"4b8d339\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3d8de2 elementor-widget elementor-widget-text-editor\" data-id=\"f3d8de2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ces syst\u00e8mes \u00e9liminent le besoin de tester et d&rsquo;ajuster manuellement en permanence plusieurs niveaux chimiques de l&rsquo;eau de la piscine sur une base quotidienne et hebdomadaire.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7523b92 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7523b92\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9019f35\" data-id=\"9019f35\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6534bd0 elementor-widget elementor-widget-heading\" data-id=\"6534bd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Certains des syst\u00e8mes de traitement d'eau de piscine les plus populaires : <\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d62c217 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d62c217\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6d7257a\" data-id=\"6d7257a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fca9028 elementor-widget elementor-widget-image\" data-id=\"fca9028\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"345\" height=\"345\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture1.jpg\" class=\"attachment-large size-large wp-image-157395\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture1.jpg 345w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture1-300x300.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture1-150x150.jpg 150w\" sizes=\"(max-width: 345px) 100vw, 345px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-28e50f7\" data-id=\"28e50f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fe1c93 elementor-widget elementor-widget-heading\" data-id=\"4fe1c93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Analyseurs de chlore, de pH, de R\u00e9dox et de temp\u00e9rature - S\u00e9rie PCA300<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba18c5b elementor-widget elementor-widget-text-editor\" data-id=\"ba18c5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Les s\u00e9ries d&rsquo;analyseurs de chlore, de pH, de R\u00e9dox et de temp\u00e9rature Hanna Instruments PCA310, PCA320, PCA330 et PCA340 sont contr\u00f4l\u00e9es par microprocesseur, des analyseurs de processus qui surveillent en continu un flux d&rsquo;\u00e9chantillon pour la teneur en chlore, le pH, le R\u00e9dox et les valeurs de temp\u00e9rature. Les analyseurs PCA utilisent la m\u00e9thode colorim\u00e9trique DPD pour d\u00e9terminer le chlore.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e1ea7b elementor-widget elementor-widget-text-editor\" data-id=\"2e1ea7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li><em>4 mod\u00e8les disponibles pour surveiller les niveaux de chlore, de pH et du R\u00e9dox<\/em><\/li>\n<li><em>Deux sorties de signal s\u00e9lectionnables s\u00e9par\u00e9es 0-20 ou 4-20 mA (PCA340 uniquement)<\/em><\/li>\n<li><em>L&rsquo;interface conviviale simplifie la configuration et la maintenance<\/em><\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c637c8 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"3c637c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.hannamaroc.com\/analyseurs-de-chlore-pca310-2-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shopping-cart\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER - PCA310-2<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1168fd4 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"1168fd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.hannamaroc.com\/analyseurs-de-chlore-de-ph-de-redox-et-de-temperature-pca320-2-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shopping-cart\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER - PCA320-2<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf89030 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"cf89030\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.hannamaroc.com\/analyseurs-de-chlore-de-ph-de-redox-et-de-temperature-pca330-2-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shopping-cart\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER - PCA330-2<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a909edd elementor-align-left elementor-widget elementor-widget-button\" data-id=\"a909edd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.hannamaroc.com\/analyseurs-de-chlore-de-ph-et-de-temperature-avec-sortie-double-pca340-2-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shopping-cart\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER - PCA340-2<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d88eae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d88eae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0359c24\" data-id=\"0359c24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8914661 elementor-widget elementor-widget-heading\" data-id=\"8914661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contr\u00f4leurs pH\/R\u00e9dox - BL122 \u2022 BL123<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56645db elementor-widget elementor-widget-text-editor\" data-id=\"56645db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>BL122 et BL123 sont con\u00e7us pour maintenir des niveaux de pH et de d\u00e9sinfectant constants dans les piscines, les bains \u00e0 remous et les spas et offrent l&rsquo;avantage suppl\u00e9mentaire de permettre la connexion \u00e0 distance et l&rsquo;acc\u00e8s aux appareils via l&rsquo;application Web Hanna Cloud. Ces contr\u00f4leurs sont disponibles en deux configurations. La version de base est le mod\u00e8le en ligne qui permet l&rsquo;installation directe de sondes et de raccords d&rsquo;injection de produits chimiques dans la tuyauterie existante. Une version mont\u00e9e sur panneau avec une cellule d&rsquo;\u00e9coulement de d\u00e9rivation est \u00e9galement disponible. La cellule de d\u00e9bit de d\u00e9rivation permet l&rsquo;\u00e9talonnage et la maintenance de la sonde sans avoir \u00e0 arr\u00eater la pompe de recirculation.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e47a13f elementor-align-left elementor-widget elementor-widget-button\" data-id=\"e47a13f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.hannamaroc.com\/controleur-ph-redox-avec-connectivite-hanna-cloud-bl122-10-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shopping-cart\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER -  BL122-10<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c43a981 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"c43a981\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.hannamaroc.com\/controleur-ph-redox-avec-connectivite-hanna-cloud-bl123-10-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shopping-cart\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER -  BL123-10<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a18f121\" data-id=\"a18f121\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83cf665 elementor-widget elementor-widget-image\" data-id=\"83cf665\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"345\" height=\"345\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture2.jpg\" class=\"attachment-large size-large wp-image-157401\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture2.jpg 345w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture2-300x300.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture2-150x150.jpg 150w\" sizes=\"(max-width: 345px) 100vw, 345px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-734ead3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"734ead3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73e0f17\" data-id=\"73e0f17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b97d71 elementor-widget elementor-widget-heading\" data-id=\"8b97d71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Laissez votre r\u00eave vous emmener au-del\u00e0 des nuages !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40ef8dd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40ef8dd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-daaa6f7\" data-id=\"daaa6f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95b1521 elementor-widget elementor-widget-text-editor\" data-id=\"95b1521\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Hanna Cloud est une application Web qui vous connecte \u00e0 des appareils de mesure tels que le BL122 et le BL123. Les mesures et le stockage des donn\u00e9es sont accessibles depuis votre PC, tablette ou t\u00e9l\u00e9phone. Les mesures, les tendances, l&rsquo;historique, les param\u00e8tres de l&rsquo;appareil, les alarmes et les messages sont transmis \u00e0 votre \u00ab tableau de bord \u00bb pendant que votre instrument mesure et contr\u00f4le votre proc\u00e9d\u00e9.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-149c932 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"149c932\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c1bd178\" data-id=\"c1bd178\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39eccbd elementor-widget elementor-widget-image\" data-id=\"39eccbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"244\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/graf.jpg\" class=\"attachment-large size-large wp-image-157137\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/graf.jpg 600w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/graf-300x122.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9685657 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9685657\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5d6cdfb\" data-id=\"5d6cdfb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09d54d8 elementor-widget elementor-widget-image\" data-id=\"09d54d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"313\" height=\"313\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture3.jpg\" class=\"attachment-large size-large wp-image-157407\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture3.jpg 313w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture3-300x300.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture3-150x150.jpg 150w\" sizes=\"(max-width: 313px) 100vw, 313px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-72273e4\" data-id=\"72273e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5466365 elementor-widget elementor-widget-heading\" data-id=\"5466365\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contr\u00f4leurs pH\/Redox - BL120 et BL121<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ea46a5 elementor-widget elementor-widget-text-editor\" data-id=\"0ea46a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><em>avec pompes d&rsquo;alimentation chimiques int\u00e9gr\u00e9es<\/em><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45546e3 elementor-widget elementor-widget-text-editor\" data-id=\"45546e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ces contr\u00f4leurs de piscine sont un syst\u00e8me complet con\u00e7u pour maintenir la qualit\u00e9 de l&rsquo;eau de d\u00e9sinfection des piscines, des bains \u00e0 remous et des spas. Ces contr\u00f4leurs sont disponibles en deux configurations. La version de base est le mod\u00e8le en ligne qui permet l&rsquo;installation directe de sondes et de raccords d&rsquo;injection de produits chimiques dans la tuyauterie existante. Une version mont\u00e9e sur panneau avec une cellule d&rsquo;\u00e9coulement de d\u00e9rivation est \u00e9galement disponible. La cellule de d\u00e9bit de d\u00e9rivation permet l&rsquo;\u00e9talonnage et la maintenance de la sonde sans avoir \u00e0 arr\u00eater la pompe de recirculation.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e859f40 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"e859f40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.hannamaroc.com\/swimming-pool-spa-controller-without-analog-output-bl120-10-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shopping-cart\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER - BL120-10<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1093269 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"1093269\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.hannamaroc.com\/ph-orp-temperature-swimming-pool-controller-with-analog-outputs-bl121-20-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shopping-cart\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER - BL121-20<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5bdcc6 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"c5bdcc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.hannamaroc.com\/swimming-pool-spa-controller-without-analog-output-bl120-10-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shopping-cart\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER - BL121-10<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-565de4d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"565de4d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9ce9e6f\" data-id=\"9ce9e6f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b9b3ca elementor-widget elementor-widget-heading\" data-id=\"9b9b3ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pool Line Contr\u00f4leur R\u00e9dox et pompe doseuse - BL101<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35cb4c6 elementor-widget elementor-widget-text-editor\" data-id=\"35cb4c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Con\u00e7u pour \u00eatre une solution peu couteuse pour les propri\u00e9taires et les entreprises d&rsquo;entretien afin de maintenir le R\u00e9dox id\u00e9al \u00e0 tout moment d&rsquo;une piscine ou d&rsquo;un bain \u00e0 remous. Le contr\u00f4leur R\u00e9dox et pompe doseuse BL101 Pool Line est une solution compl\u00e8te avec \u00e0 la fois un contr\u00f4leur de processus et une pompe doseuse chimique. Ins\u00e9rez simplement la sonde et la vanne d&rsquo;injection en ligne avec la pompe de recirculation et fournissez l&rsquo;oxydant (c&rsquo;est-\u00e0-dire le chlore) \u00e0 doser.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b50be2a elementor-widget elementor-widget-text-editor\" data-id=\"b50be2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li><em>Solution tout-en-un pour maintenir la valeur R\u00e9dox appropri\u00e9e<\/em><\/li>\n<li><em>Sonde de process industriel avec1\/2<\/em><em>\u2033<\/em><em> Filetages NPT pour insertion dans la ligne de recirculation<\/em><\/li>\n<li><em>Entr\u00e9e pour r\u00e9gulateur de niveau ou interrupteur de d\u00e9bit<\/em><\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc4836e elementor-align-left elementor-widget elementor-widget-button\" data-id=\"dc4836e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.hannamaroc.com\/controleur-redox-et-pompe-doseuse-bl101-10-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shopping-cart\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER - BL101-10<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2d1d89c\" data-id=\"2d1d89c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab381ef elementor-widget elementor-widget-image\" data-id=\"ab381ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"299\" height=\"299\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture4.jpg\" class=\"attachment-large size-large wp-image-157413\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture4.jpg 299w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture4-150x150.jpg 150w\" sizes=\"(max-width: 299px) 100vw, 299px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e324dfb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e324dfb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e5d3b11\" data-id=\"e5d3b11\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-767ced7 elementor-widget elementor-widget-image\" data-id=\"767ced7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"365\" height=\"365\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture5.jpg\" class=\"attachment-large size-large wp-image-157419\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture5.jpg 365w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture5-300x300.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture5-150x150.jpg 150w\" sizes=\"(max-width: 365px) 100vw, 365px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9c76070\" data-id=\"9c76070\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa17008 elementor-widget elementor-widget-heading\" data-id=\"aa17008\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contr\u00f4leur de pH et pompe doseuse BL100<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f11a87 elementor-widget elementor-widget-text-editor\" data-id=\"0f11a87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>est un syst\u00e8me con\u00e7u pour maintenir le pH des piscines, des bains \u00e0 remous et des spas. G\u00e9n\u00e9ralement, le chlore, qu&rsquo;il soit liquide ou solide, est alcalin et augmentera le pH de l&rsquo;eau \u00e0 laquelle il est ajout\u00e9. Lorsque le pH augmente au-dessus de pH 7,4, une forme de chlore connue sous le nom d&rsquo;ion hypochlorite (OCl-) augmente. Cette forme de chlore est 100 fois moins efficace pour tuer les bact\u00e9ries que l&rsquo;autre forme de chlore connue sous le nom d&rsquo;acide hypochloreux (HOCl). Pour cette raison, il est important de maintenir le niveau de pH correct afin de s&rsquo;assurer que la forme d&rsquo;acide hypochloreux la plus puissante est disponible pour la d\u00e9sinfection. Le BL100 a \u00e9t\u00e9 d\u00e9velopp\u00e9 pour \u00eatre une solution peu co\u00fbteuse permettant au consommateur de maintenir le pH id\u00e9al \u00e0 tout moment. Ins\u00e9rez simplement la sonde et la vanne d&rsquo;injection en ligne avec la pompe de recirculation et fournissez le produit chimique \u00e0 doser.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca2378d elementor-widget elementor-widget-text-editor\" data-id=\"ca2378d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li><em>Solution tout-en-un pour maintenir le bon pH<\/em><\/li>\n<li><em>Sonde de process industriel avec1\/2<\/em><em>\u2033<\/em><em> Filetages NPT pour insertion dans la ligne de recirculation<\/em><\/li>\n<li><em>Entr\u00e9e pour r\u00e9gulateur de niveau ou interrupteur de d\u00e9bit<\/em><\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77f9be9 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"77f9be9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.hannamaroc.com\/controleur-de-ph-et-pompe-doseuse-bl100-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shopping-cart\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER - BL100-10<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9fd0957 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9fd0957\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b2573e\" data-id=\"1b2573e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-004c610 elementor-widget elementor-widget-text-editor\" data-id=\"004c610\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Une fois que vous avez \u00e9tabli les options d&rsquo;assainissement, tout ce que vous avez \u00e0 faire est de tester votre eau r\u00e9guli\u00e8rement afin qu&rsquo;elle reste propre et adapt\u00e9e aux baigneurs.<br \/>Selon l&rsquo;option d&rsquo;assainissement que vous avez choisie (automatique ou manuelle) pour la d\u00e9sinfection, il existe plusieurs options pour tester l&rsquo;eau avec des appareils portables pratiques.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b7c225 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b7c225\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9d7d6b6\" data-id=\"9d7d6b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0c4e7e elementor-widget elementor-widget-heading\" data-id=\"e0c4e7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HANNA POOL LINE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2bd2128 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2bd2128\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-422ccfc\" data-id=\"422ccfc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c603975 elementor-widget elementor-widget-image\" data-id=\"c603975\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"147\" height=\"190\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Picture6.png\" class=\"attachment-large size-large wp-image-157425\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-31cf116\" data-id=\"31cf116\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3622b0 elementor-widget elementor-widget-heading\" data-id=\"f3622b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HANNA Instruments <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6eee95 elementor-widget elementor-widget-text-editor\" data-id=\"c6eee95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>est fier de pr\u00e9senter notre nouvelle gamme d&rsquo;instruments d\u00e9di\u00e9s sp\u00e9cifiquement aux piscines et spas \u2013 POOL LINE.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6666f6 elementor-widget elementor-widget-text-editor\" data-id=\"c6666f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Notre nouvelle ligne a \u00e9t\u00e9 d\u00e9velopp\u00e9e dans le respect de tous les param\u00e8tres essentiels couverts.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6888b4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6888b4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a8ae9f\" data-id=\"4a8ae9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13c5026 elementor-widget elementor-widget-image\" data-id=\"13c5026\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"395\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Pool-Line-pic-600x395.jpg\" class=\"attachment-large size-large wp-image-157437\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Pool-Line-pic-600x395.jpg 600w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Pool-Line-pic-300x198.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Pool-Line-pic-768x506.jpg 768w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/Pool-Line-pic.jpg 1440w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-942a903 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"942a903\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-487cc50\" data-id=\"487cc50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c76616 elementor-widget elementor-widget-heading\" data-id=\"6c76616\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pool Line \u00c9quipement Portatif<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c987ccd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c987ccd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69aadcd\" data-id=\"69aadcd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2241750 elementor-widget elementor-widget-heading\" data-id=\"2241750\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HANNA Pool Line int\u00e8gre une gamme compl\u00e8te d'\u00e9quipements de test <\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f9ccc3f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f9ccc3f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30bf5dd\" data-id=\"30bf5dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfd4300 elementor-widget elementor-widget-text-editor\" data-id=\"cfd4300\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li><strong>Photom\u00e8tre <\/strong>est con\u00e7u pour mesurer le pH, l&rsquo;alcalinit\u00e9, le chlore libre et total et l&rsquo;acide cyanurique dans les piscines, les bains \u00e0 remous et les spas.<\/li>\n<li><strong>Pool Line Testeurs de pH\/R\u00e9dox\/Temp\u00e9rature<\/strong><\/li>\n<li><strong>Thermom\u00e8tres<\/strong><\/li>\n<li><strong>Turbidim\u00e8tres<\/strong><\/li>\n<li><strong>Thermo-Hygrom\u00e8tres<\/strong><\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-957289d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"957289d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0718524\" data-id=\"0718524\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdf97eb elementor-widget elementor-widget-heading\" data-id=\"cdf97eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ainsi, une fois que vous avez termin\u00e9 les tests et que vos niveaux sont dans une plage acceptable, vous pouvez profiter de votre moment de d\u00e9tente sans stress !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8740c9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8740c9f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-12a78bd\" data-id=\"12a78bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49b26fb elementor-widget elementor-widget-text-editor\" data-id=\"49b26fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"background: white;\"><span style=\"font-family: 'Soho Gothic Pro',sans-serif; color: black;\">Auteur: Nives Vincekovi\u0107 Budor, mag.ing.chem.ing.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1703d65 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1703d65\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-286c5e9\" data-id=\"286c5e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-970f1d5 elementor-widget elementor-widget-text-editor\" data-id=\"970f1d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Sources:<\/strong><br \/><a href=\"https:\/\/www.stampar.hr\/hr\/hiperkloriranje-bazenske-vode\">https:\/\/www.stampar.hr\/hr\/hiperkloriranje-bazenske-vode<\/a><br \/><a href=\"https:\/\/www.sciencedirect.com\/topics\/engineering\/combined-chlorine\">https:\/\/www.sciencedirect.com\/topics\/engineering\/combined-chlorine<\/a><br \/><a href=\"https:\/\/chlorine.americanchemistry.com\/Science-Center\/Chlorine-Compound-of-the-Month-Library\/Chloramines-Understanding-Pool-Smell\/\">https:\/\/chlorine.americanchemistry.com\/Science-Center\/Chlorine-Compound-of-the-Month-Library\/Chloramines-Understanding-Pool-Smell\/<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Il n&rsquo;est jamais trop t\u00f4t (ni trop tard) pour suivre l&rsquo;entretien de votre piscine. Vous [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":157376,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[393],"tags":[472],"class_list":["post-157918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eau","tag-piscines"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment pr\u00e9parer sa piscine pour la nouvelle saison ? - Hanna Instruments Maroc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment pr\u00e9parer sa piscine pour la nouvelle saison ? - Hanna Instruments Maroc\" \/>\n<meta property=\"og:description\" content=\"Il n&rsquo;est jamais trop t\u00f4t (ni trop tard) pour suivre l&rsquo;entretien de votre piscine. Vous [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/\" \/>\n<meta property=\"og:site_name\" content=\"Hanna Instruments Maroc\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-26T15:15:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-10T10:43:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/PoolFeaturedImage.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Milan Petrovi\u0107\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Milan Petrovi\u0107\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\\\/\"},\"author\":{\"name\":\"Milan Petrovi\u0107\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/person\\\/6872d7596a0a8c85e08ebf8440a39296\"},\"headline\":\"Comment pr\u00e9parer sa piscine pour la nouvelle saison ?\",\"datePublished\":\"2022-01-26T15:15:03+00:00\",\"dateModified\":\"2022-10-10T10:43:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\\\/\"},\"wordCount\":1865,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/PoolFeaturedImage.jpg\",\"keywords\":[\"Piscines\"],\"articleSection\":[\"Eau\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\\\/\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\\\/\",\"name\":\"Comment pr\u00e9parer sa piscine pour la nouvelle saison ? - Hanna Instruments Maroc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/PoolFeaturedImage.jpg\",\"datePublished\":\"2022-01-26T15:15:03+00:00\",\"dateModified\":\"2022-10-10T10:43:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/PoolFeaturedImage.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/PoolFeaturedImage.jpg\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog home\",\"item\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment pr\u00e9parer sa piscine pour la nouvelle saison ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\",\"name\":\"Hanna Instruments Africa\",\"description\":\"pH M\u00e8tres, Photom\u00e8tres, Titrateurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\",\"name\":\"Hanna Instruments\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/hs-logo.png\",\"contentUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/hs-logo.png\",\"width\":733,\"height\":225,\"caption\":\"Hanna Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/person\\\/6872d7596a0a8c85e08ebf8440a39296\",\"name\":\"Milan Petrovi\u0107\",\"sameAs\":[\"http:\\\/\\\/blog.hannaservice.eu\"],\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/author\\\/mpetrovic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment pr\u00e9parer sa piscine pour la nouvelle saison ? - Hanna Instruments Maroc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment pr\u00e9parer sa piscine pour la nouvelle saison ? - Hanna Instruments Maroc","og_description":"Il n&rsquo;est jamais trop t\u00f4t (ni trop tard) pour suivre l&rsquo;entretien de votre piscine. Vous [&hellip;]","og_url":"https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/","og_site_name":"Hanna Instruments Maroc","article_published_time":"2022-01-26T15:15:03+00:00","article_modified_time":"2022-10-10T10:43:30+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/PoolFeaturedImage.jpg","type":"image\/jpeg"}],"author":"Milan Petrovi\u0107","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Milan Petrovi\u0107","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/#article","isPartOf":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/"},"author":{"name":"Milan Petrovi\u0107","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/person\/6872d7596a0a8c85e08ebf8440a39296"},"headline":"Comment pr\u00e9parer sa piscine pour la nouvelle saison ?","datePublished":"2022-01-26T15:15:03+00:00","dateModified":"2022-10-10T10:43:30+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/"},"wordCount":1865,"publisher":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/PoolFeaturedImage.jpg","keywords":["Piscines"],"articleSection":["Eau"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/","url":"https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/","name":"Comment pr\u00e9parer sa piscine pour la nouvelle saison ? - Hanna Instruments Maroc","isPartOf":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/#primaryimage"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/PoolFeaturedImage.jpg","datePublished":"2022-01-26T15:15:03+00:00","dateModified":"2022-10-10T10:43:30+00:00","breadcrumb":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/#primaryimage","url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/PoolFeaturedImage.jpg","contentUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/01\/PoolFeaturedImage.jpg","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/blog.hannaservice.eu\/fr\/comment-preparer-sa-piscine-pour-la-nouvelle-saison-de-piscine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog home","item":"https:\/\/blog.hannaservice.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment pr\u00e9parer sa piscine pour la nouvelle saison ?"}]},{"@type":"WebSite","@id":"https:\/\/blog.hannaservice.eu\/fr\/#website","url":"https:\/\/blog.hannaservice.eu\/fr\/","name":"Hanna Instruments Africa","description":"pH M\u00e8tres, Photom\u00e8tres, Titrateurs","publisher":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.hannaservice.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization","name":"Hanna Instruments","url":"https:\/\/blog.hannaservice.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/01\/hs-logo.png","contentUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/01\/hs-logo.png","width":733,"height":225,"caption":"Hanna Instruments"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/person\/6872d7596a0a8c85e08ebf8440a39296","name":"Milan Petrovi\u0107","sameAs":["https:\/\/blog.hannaservice.eu"],"url":"https:\/\/blog.hannaservice.eu\/fr\/author\/mpetrovic\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/157918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/comments?post=157918"}],"version-history":[{"count":22,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/157918\/revisions"}],"predecessor-version":[{"id":160443,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/157918\/revisions\/160443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/media\/157376"}],"wp:attachment":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/media?parent=157918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/categories?post=157918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/tags?post=157918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}