{"id":175152,"date":"2022-07-04T08:36:02","date_gmt":"2022-07-04T08:36:02","guid":{"rendered":"https:\/\/blog.hannaservice.eu\/production-de-chrysanthemes-preparation-a-la-transplantation\/"},"modified":"2022-10-10T09:45:34","modified_gmt":"2022-10-10T09:45:34","slug":"production-de-chrysanthemes-preparation-a-la-transplantation","status":"publish","type":"post","link":"https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/","title":{"rendered":"Production de chrysanth\u00e8mes \u2013 pr\u00e9paration \u00e0 la transplantation"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"175152\" class=\"elementor elementor-175152 elementor-174471\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b61aa1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b61aa1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b198f97\" data-id=\"b198f97\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22fb203 elementor-widget elementor-widget-heading\" data-id=\"22fb203\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les chrysanth\u00e8mes sont les reines de l'automne et la d\u00e9coration de tous les jardins.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-458f8fa elementor-widget elementor-widget-text-editor\" data-id=\"458f8fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLes chrysanth\u00e8mes en tant que fleurs qui ornent les jardins jusqu&rsquo;\u00e0 la fin de l&rsquo;automne en Croatie et dans les environs, ont le plus souvent un lien en tant que fleurs port\u00e9es au cimeti\u00e8re alors que dans le reste du monde les chrysanth\u00e8mes n&rsquo;ont pas un tel statut.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fb3e52 elementor-widget elementor-widget-text-editor\" data-id=\"8fb3e52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLes chrysanth\u00e8mes tels que les boutures et les pots \u00e0 petites fleurs d\u00e9corent les jardins, les terrasses et les maisons et nous ravissent par leurs couleurs.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f301112\" data-id=\"f301112\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-adcb4a3 elementor-widget elementor-widget-image\" data-id=\"adcb4a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"438\" height=\"600\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-1-438x600.jpg\" class=\"attachment-large size-large wp-image-174481\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-1-438x600.jpg 438w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-1-219x300.jpg 219w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-1.jpg 472w\" sizes=\"(max-width: 438px) 100vw, 438px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2509dd7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2509dd7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a166fe\" data-id=\"2a166fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3cbf17 elementor-widget elementor-widget-text-editor\" data-id=\"a3cbf17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLes chrysanth\u00e8mes sont des vivaces. Celles vendues comme plantes en pot sont trait\u00e9es comme des annuelles, mais apr\u00e8s la floraison, une fertilisation et une taille appropri\u00e9es l&rsquo;ann\u00e9e prochaine nous raviront avec des couleurs.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a543a11 elementor-widget elementor-widget-text-editor\" data-id=\"a543a11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tApr\u00e8s avoir fait pousser des semis au printemps, nous arrivons \u00e0 la partie la plus critique \u00e0 la fin juillet, et c&rsquo;est le repiquage dans des zones ouvertes ou abrit\u00e9es.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db49d36 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db49d36\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4845e0c\" data-id=\"4845e0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-452c1da elementor-widget elementor-widget-text-editor\" data-id=\"452c1da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tPar cons\u00e9quent, lors de la pr\u00e9paration du sol pour le repiquage et la culture des chrysanth\u00e8mes, des pr\u00e9cautions doivent \u00eatre prises et tout doit \u00eatre pr\u00e9par\u00e9 dans le rapport le plus id\u00e9al \u00e0 partir des nutriments.\nau pH.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eaa3b49 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"eaa3b49\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-891a060\" data-id=\"891a060\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-296d848 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"296d848\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-720ed11\" data-id=\"720ed11\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab6079e elementor-widget elementor-widget-text-editor\" data-id=\"ab6079e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLes chrysanth\u00e8mes sont des reines du stress pour les producteurs de fleurs, mais ce sont aussi des plantes \u00e0 haute valeur de revenu.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-062b2fb elementor-widget elementor-widget-text-editor\" data-id=\"062b2fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tR\u00e9action id\u00e9ale du pH du sol pour les chrysanth\u00e8mes dans le substrat (m\u00e9langes sp\u00e9ciaux)\net les sols de jardin ont un pH de 6 \u00e0 7,2, ils sont donc id\u00e9aux pour les sols mi-lourds\nsols limoneux avec des r\u00e9actions faiblement acides \u00e0 alcalines qui, sur le continent\nla partie en a assez.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c77278 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c77278\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0f88ec7\" data-id=\"0f88ec7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ffc171 elementor-widget elementor-widget-heading\" data-id=\"9ffc171\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HI98168<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-940b040 elementor-widget elementor-widget-text-editor\" data-id=\"940b040\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong>pH-m\u00e8tre de sol professionnel<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d69ea7b\" data-id=\"d69ea7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-edc264d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"edc264d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2cc4ff3\" data-id=\"2cc4ff3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-303a33e elementor-widget elementor-widget-text-editor\" data-id=\"303a33e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLe HI98168 est un pH-m\u00e8tre robuste, \u00e9tanche et portable qui permet la mesure directe du pH du sol. Cet appareil de mesure est fourni avec une \u00e9lectrode de pH sp\u00e9cialis\u00e9e dot\u00e9e d&rsquo;une pointe conique robuste pour une insertion dans le sol.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79d7022 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79d7022\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-63b6cff\" data-id=\"63b6cff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93f68b1 elementor-widget elementor-widget-image\" data-id=\"93f68b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"438\" height=\"438\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI98168.jpg\" class=\"attachment-large size-large wp-image-174514\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI98168.jpg 438w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI98168-300x300.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI98168-150x150.jpg 150w\" sizes=\"(max-width: 438px) 100vw, 438px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00c3cde elementor-align-center elementor-widget elementor-widget-button\" data-id=\"00c3cde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/www.hannamaroc.com\/professional-soil-ph-meter-groline-hi98168-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9d43d61\" data-id=\"9d43d61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-182bc10 elementor-widget elementor-widget-text-editor\" data-id=\"182bc10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tEn plus d&rsquo;\u00eatre fourni avec une \u00e9lectrode de pH unique con\u00e7ue pour l&rsquo;analyse du sol, le HI98168 poss\u00e8de la fonction unique CAL Check \u2122 de Hanna qui alerte l&rsquo;utilisateur des probl\u00e8mes potentiels pendant le processus d&rsquo;\u00e9talonnage. Ceci est tr\u00e8s important car il est probable que la sonde sera recouverte de terre. Ce rev\u00eatement peut facilement entra\u00eener des erreurs de mesure du pH. En comparant les donn\u00e9es d&rsquo;\u00e9talonnage pr\u00e9c\u00e9dentes \u00e0 l&rsquo;\u00e9talonnage actuel, l&rsquo;appareil informera l&rsquo;utilisateur, avec des invites d&rsquo;affichage, lorsque la sonde doit \u00eatre nettoy\u00e9e, remplac\u00e9e ou si le tampon pH peut \u00eatre contamin\u00e9. Apr\u00e8s l&rsquo;\u00e9talonnage, l&rsquo;\u00e9tat g\u00e9n\u00e9ral de la sonde s&rsquo;affiche \u00e0 l&rsquo;\u00e9cran sous forme de pourcentage. L&rsquo;\u00e9tat de la sonde est affect\u00e9 \u00e0 la fois par les caract\u00e9ristiques de d\u00e9calage et de pente de l&rsquo;\u00e9lectrode de pH, qui peuvent toutes deux \u00eatre trouv\u00e9es dans les donn\u00e9es BPL, y compris avec les lectures stock\u00e9es dans l&rsquo;appareil de mesure ou transf\u00e9r\u00e9es vers un PC.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20c7989 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20c7989\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4067040\" data-id=\"4067040\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c23d6b elementor-widget elementor-widget-text-editor\" data-id=\"3c23d6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Connecteur Quick Connect DIN<\/li>\n<li>Connexion USB pour le transfert de donn\u00e9es<\/li>\n<li>Bouton d&rsquo;aide d\u00e9di\u00e9<\/li>\n<li>Pr\u00e9cision \u00b10,002 pH<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9e47a7f\" data-id=\"9e47a7f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3b4ddc elementor-widget elementor-widget-text-editor\" data-id=\"e3b4ddc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Livr\u00e9 avec toutes les solutions et piles n\u00e9cessaires &#8211; tout ce dont vous avez besoin pour commencer \u00e0 mesurer imm\u00e9diatement.<\/li>\n<li>\u00c9lectrode sp\u00e9cialis\u00e9e pour la v\u00e9rification ponctuelle du pH du sol et des boues de sol.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-642fc87 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"642fc87\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3875c36\" data-id=\"3875c36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c227e2 elementor-widget elementor-widget-image\" data-id=\"4c227e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"457\" height=\"457\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Kofer-1.jpg\" class=\"attachment-large size-large wp-image-174532\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Kofer-1.jpg 457w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Kofer-1-300x300.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Kofer-1-150x150.jpg 150w\" sizes=\"(max-width: 457px) 100vw, 457px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9cccad8\" data-id=\"9cccad8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fec43a0 elementor-widget elementor-widget-image\" data-id=\"fec43a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"453\" height=\"453\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Kofer-2.jpg\" class=\"attachment-large size-large wp-image-174538\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Kofer-2.jpg 453w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Kofer-2-300x300.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Kofer-2-150x150.jpg 150w\" sizes=\"(max-width: 453px) 100vw, 453px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d7534fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d7534fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9646683\" data-id=\"9646683\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0aaa4e9 elementor-widget elementor-widget-text-editor\" data-id=\"0aaa4e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLa fertilisation est recommand\u00e9e pour un contr\u00f4le et une croissance r\u00e9ussie.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25a6bb7 elementor-widget elementor-widget-text-editor\" data-id=\"25a6bb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tAvec des engrais solubles dans l&rsquo;eau \u00e0 chaque cycle d&rsquo;irrigation \u00e0 une concentration de 200 ppm d&rsquo;engrais NPK complexes N.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7124f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7124f1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-23d4cd4\" data-id=\"23d4cd4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f661bd elementor-widget elementor-widget-heading\" data-id=\"0f661bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HI9814<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54f088f elementor-widget elementor-widget-text-editor\" data-id=\"54f088f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong>Instrument Portatif pH\/EC\/TDS\/\u00b0C<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-72ba325\" data-id=\"72ba325\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf18358 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf18358\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b1853f8\" data-id=\"b1853f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e6097e elementor-widget elementor-widget-image\" data-id=\"8e6097e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"266\" height=\"525\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI9814.jpg\" class=\"attachment-large size-large wp-image-174556\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI9814.jpg 266w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI9814-152x300.jpg 152w\" sizes=\"(max-width: 266px) 100vw, 266px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e8fd00 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3e8fd00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/www.hannamaroc.com\/ph-ec-tds-temperature-meter-hi9814-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-822fc66\" data-id=\"822fc66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-090fcb6 elementor-widget elementor-widget-text-editor\" data-id=\"090fcb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tHI9814 est un indicateur de pH, de conductivit\u00e9, de solides dissous totaux et de temp\u00e9rature durable et portable pour la plupart des mesures rencontr\u00e9es dans les applications hydroponiques, aquaponiques ou agricoles g\u00e9n\u00e9rales. Toutes les op\u00e9rations et tous les r\u00e9glages sont effectu\u00e9s via seulement deux boutons et le bo\u00eetier est \u00e9tanche et class\u00e9 pour les conditions IP67. Les fonctionnalit\u00e9s s\u00e9lectionnables par l&rsquo;utilisateur incluent des facteurs TDS s\u00e9lectionnables de 0,5 et 0,7 ainsi qu&rsquo;un arr\u00eat automatique apr\u00e8s 8 minutes ou 60 minutes pour prolonger la dur\u00e9e de vie de la batterie.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f982f9b elementor-widget elementor-widget-image\" data-id=\"f982f9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"396\" height=\"307\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-3-cvet.jpg\" class=\"attachment-large size-large wp-image-174562\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-3-cvet.jpg 396w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-3-cvet-300x233.jpg 300w\" sizes=\"(max-width: 396px) 100vw, 396px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-997512e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"997512e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-05ace45\" data-id=\"05ace45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93cc121 elementor-widget elementor-widget-heading\" data-id=\"93cc121\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HI98318<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98278e1 elementor-widget elementor-widget-text-editor\" data-id=\"98278e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong>Testeur EC\/TDS<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ec5b45c\" data-id=\"ec5b45c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dd5a41 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5dd5a41\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8290958\" data-id=\"8290958\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ba3f72 elementor-widget elementor-widget-text-editor\" data-id=\"4ba3f72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLe HI98318 est notre dernier compteur de poche pour mesurer l&rsquo;EC\/TDS d&rsquo;une solution nutritive hydroponique. Ce compteur d&rsquo;aspect moderne ne mesure que 0,7&Prime; d&rsquo;\u00e9paisseur et est extr\u00eamement ergonomique, s&rsquo;adaptant confortablement dans votre main. Le HI98318 dispose d&rsquo;un tr\u00e8s grand \u00e9cran LCD facile \u00e0 lire qui affiche \u00e0 la fois EC ou TDS et la temp\u00e9rature ainsi que des indicateurs d&rsquo;\u00e9talonnage, de stabilit\u00e9 et de batterie faible. Toutes les op\u00e9rations sont simplifi\u00e9es \u00e0 deux boutons. L&rsquo;un sert \u00e0 allumer\/\u00e9teindre l&rsquo;appareil et l&rsquo;autre \u00e0 l&rsquo;\u00e9talonnage automatique en un point.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-033dda2 elementor-widget elementor-widget-text-editor\" data-id=\"033dda2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Capteur en graphite pour un effet de polarisation r\u00e9duit<\/li>\n<li>Fonctionnement \u00e0 deux boutons<\/li>\n<li>Mode d&rsquo;\u00e9talonnage rapide \u00e0 l&rsquo;aide de la solution Hanna pH\/EC Quick Cal<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5c30e57\" data-id=\"5c30e57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d5c843 elementor-widget elementor-widget-image\" data-id=\"1d5c843\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"230\" height=\"566\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI98318.jpg\" class=\"attachment-large size-large wp-image-174571\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI98318.jpg 230w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI98318-122x300.jpg 122w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a06da3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5a06da3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/www.hannamaroc.com\/testeur-ec-tds-hi98318-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9cb1ca9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9cb1ca9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5af366b\" data-id=\"5af366b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dab0683 elementor-widget elementor-widget-text-editor\" data-id=\"dab0683\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLes concentrations de repiquage peuvent \u00eatre de 200-300 ppm d&rsquo;engrais NPK apr\u00e8s la plantation (engrais NPK \u00e9quilibr\u00e9 15-15-15 \/ 20-10-15 ou sp\u00e9cifique pour les chrysanth\u00e8mes).\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcd6427 elementor-widget elementor-widget-text-editor\" data-id=\"bcd6427\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Des micro \u00e9l\u00e9ments doivent toujours \u00eatre ajout\u00e9s car nous voulons que toutes les plantes aient de belles feuilles vertes bien form\u00e9es ainsi que des fleurs de belles couleurs. Il vous suffit de faire attention \u00e0 votre alimentation en phosphore car l&rsquo;exc\u00e8s provoque un allongement des plantes et cela n&rsquo;a aucune valeur marchande.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2266aa6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2266aa6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-54a63e7\" data-id=\"54a63e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10acbec elementor-widget elementor-widget-heading\" data-id=\"10acbec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HI83325-02 <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6981a65 elementor-widget elementor-widget-text-editor\" data-id=\"6981a65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong>Photom\u00e8tre d&rsquo;analyse des nutriments <\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d623435\" data-id=\"d623435\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76db2b6 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76db2b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-330fa4a\" data-id=\"330fa4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf12a51 elementor-widget elementor-widget-image\" data-id=\"cf12a51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"404\" height=\"404\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI83325-02.jpg\" class=\"attachment-large size-large wp-image-174589\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI83325-02.jpg 404w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI83325-02-300x300.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI83325-02-150x150.jpg 150w\" sizes=\"(max-width: 404px) 100vw, 404px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e919362 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e919362\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/www.hannamaroc.com\/photometre-d-analyse-des-nutriments-hi83325-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8b6fe75\" data-id=\"8b6fe75\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7044e82 elementor-widget elementor-widget-text-editor\" data-id=\"7044e82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tHI83325 est un photom\u00e8tre multiparam\u00e8tre compact pour une utilisation en laboratoire environnemental ou sur le terrain. Le compteur est l&rsquo;un des photom\u00e8tres les plus avanc\u00e9s disponibles avec une conception optique innovante qui utilise un d\u00e9tecteur de r\u00e9f\u00e9rence et une lentille de focalisation pour \u00e9liminer les erreurs dues aux changements de la source lumineuse et aux imperfections de la cuvette en verre. Ce compteur dispose de 9 m\u00e9thodes programm\u00e9es diff\u00e9rentes mesurant 8 param\u00e8tres cl\u00e9s de la qualit\u00e9 de l&rsquo;eau des \u00e9l\u00e9ments nutritifs des plantes:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c1dbe8 elementor-widget elementor-widget-text-editor\" data-id=\"7c1dbe8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li><strong>Ammoniaque<\/strong><\/li>\n<li><strong>Nitrate<\/strong><\/li>\n<li><strong>Phosphate<\/strong><\/li>\n<li><strong>Potassium<\/strong><\/li>\n<li><strong>Sulfate<\/strong><\/li>\n<li><strong>Calcium<\/strong><\/li>\n<li><strong>Fer<\/strong><\/li>\n<li><strong>Magn\u00e9sium<\/strong><\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54ab152 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54ab152\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e37771\" data-id=\"2e37771\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79f5120 elementor-widget elementor-widget-text-editor\" data-id=\"79f5120\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tPour \u00e9conomiser de l&rsquo;espace pr\u00e9cieux sur la paillasse de laboratoire, le HI83325 se double d&rsquo;un pH-m\u00e8tre professionnel avec son entr\u00e9e d&rsquo;\u00e9lectrode num\u00e9rique pH\/temp\u00e9rature. D\u00e9sormais, un m\u00e8tre peut \u00eatre utilis\u00e9 \u00e0 la fois pour les mesures photom\u00e9triques et de pH.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83c189a elementor-widget elementor-widget-text-editor\" data-id=\"83c189a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tCe qui ne devrait pas \u00eatre autoris\u00e9, c&rsquo;est de laisser la plante sans eau, surtout dans\nle d\u00e9but de la production et \u00e0 la transplantation.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a18aa6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a18aa6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9b0a745\" data-id=\"9b0a745\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1a146a elementor-widget elementor-widget-text-editor\" data-id=\"c1a146a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tConseil de Hanna:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a88c870 elementor-widget elementor-widget-text-editor\" data-id=\"a88c870\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLors de la mesure de l&rsquo;EC dans le sol et le sol, prendre des mesures juste \u00e0 c\u00f4t\u00e9 des plantes ainsi que plus loin. L\u2019humidit\u00e9, les \u00e9l\u00e9ments nutritifs et le pH peuvent varier consid\u00e9rablement dans une zone plant\u00e9e. Cela signifie un peu plus de travail, mais vous appr\u00e9cierez \u00eatre en mesure d\u2019obtenir des r\u00e9sultats qui repr\u00e9sentent mieux votre zone de plantation.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59d5018 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59d5018\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fbeb3b9\" data-id=\"fbeb3b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1738a8 elementor-widget elementor-widget-heading\" data-id=\"e1738a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HI98331<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86b0113 elementor-widget elementor-widget-text-editor\" data-id=\"86b0113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong>Testeur EC direct du sol Soil Test\u2122 <\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ee5bb91\" data-id=\"ee5bb91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0346b53 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0346b53\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4990327\" data-id=\"4990327\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5860942 elementor-widget elementor-widget-image\" data-id=\"5860942\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"322\" height=\"559\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI98331.jpg\" class=\"attachment-large size-large wp-image-174601\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI98331.jpg 322w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI98331-173x300.jpg 173w\" sizes=\"(max-width: 322px) 100vw, 322px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba20d55 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ba20d55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/www.hannamaroc.com\/le-testeur-de-conductivite-directe-dans-le-sol-hi98331-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bc87ae7\" data-id=\"bc87ae7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5361b1 elementor-widget elementor-widget-text-editor\" data-id=\"c5361b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tTesteur EC direct du sol Soil Test\u2122 \u2013 HI98331 est un testeur de poche robuste et fiable qui offre des lectures rapides et pr\u00e9cises. Testeur EC direct du sol Soil Test\u2122 \u2013 HI98331 dispose d&rsquo;une sonde de p\u00e9n\u00e9tration en acier inoxydable pour la mesure directe de la conductivit\u00e9 dans les sols. Avec une taille compacte, un bouton unique et un \u00e9talonnage automatique, Testeur de Sol est un excellent choix pour prendre des mesures directes de conductivit\u00e9 dans le sol.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4d3590 elementor-widget elementor-widget-text-editor\" data-id=\"a4d3590\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDans le cas des chrysanth\u00e8mes, il est \u00e9galement sp\u00e9cifique d&rsquo;ajouter des fongicides PPP dans la solution d&rsquo;irrigation. Les fongicides PPP utilis\u00e9s sont \u00e0 base de captane et d&rsquo;insecticides syst\u00e9miques pour pr\u00e9venir les pertes ult\u00e9rieures dues aux ravageurs et aux maladies. S&rsquo;il est laiss\u00e9 sec (faible EC) dans les premiers stades de la production sera donc r\u00e9duit\nla ramification des chrysanth\u00e8mes et leur croissance. En phase finale de production\nun s\u00e9chage doux peut \u00eatre utilis\u00e9 pour durcir les plantes et leur donner une hauteur et une floraison uniformes. Par cons\u00e9quent, la mesure de l&rsquo;EC directement dans le sol aide les producteurs dans leurs d\u00e9cisions et leur planification.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49ecc3d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49ecc3d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a77bc8\" data-id=\"4a77bc8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1854cc3 elementor-widget elementor-widget-text-editor\" data-id=\"1854cc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tAu d\u00e9part, la temp\u00e9rature \u00e0 l&rsquo;int\u00e9rieur de la zone prot\u00e9g\u00e9e doit \u00eatre de 20\u00b0C &#8211; 25\u00b0C un maximum journalier de 25\u00b0C ce qui impose aux industriels un grand besoin de surveillance constante et les temp\u00e9ratures nocturnes ne doivent pas \u00eatre inf\u00e9rieures \u00e0 18\u00b0C.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff9d2ca elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"ff9d2ca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b4a5739\" data-id=\"b4a5739\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58af793 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58af793\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8344a51\" data-id=\"8344a51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d6546a elementor-widget elementor-widget-heading\" data-id=\"8d6546a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HI148<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86940d1 elementor-widget elementor-widget-text-editor\" data-id=\"86940d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong>Enregistreur de temp\u00e9rature <\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-21cfc85\" data-id=\"21cfc85\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9514b86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9514b86\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-527f8bc\" data-id=\"527f8bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2a78f2 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"b2a78f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:60}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"377\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI148-600x377.jpg\" class=\"attachment-large size-large wp-image-174623\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI148-600x377.jpg 600w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI148-300x189.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI148-768x483.jpg 768w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI148.jpg 861w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a04d83b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a04d83b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-98328c8\" data-id=\"98328c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1cc1fd elementor-widget elementor-widget-text-editor\" data-id=\"d1cc1fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tRapide \u00e0 installer, simple \u00e0 utiliser, le HI148 est un enregistreur de donn\u00e9es id\u00e9al pour surveiller et enregistrer la temp\u00e9rature dans des applications telles que la transformation des aliments, le transport, les mus\u00e9es et l&rsquo;horticulture.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e81160 elementor-widget elementor-widget-text-editor\" data-id=\"4e81160\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Choisissez entre 4 mod\u00e8les et stockez jusqu&rsquo;\u00e0 16 000 enregistrements !<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70cb8e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70cb8e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34403c5\" data-id=\"34403c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9eff0db elementor-widget elementor-widget-text-editor\" data-id=\"9eff0db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Conception fine et robuste<\/li>\n<li>Plusieurs options de capteur<\/li>\n<li>\u00c9cran LCD programmable<\/li>\n<li>Connectivit\u00e9 PC<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0a5e314\" data-id=\"0a5e314\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3321914 elementor-widget elementor-widget-text-editor\" data-id=\"3321914\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Param\u00e8tres de programme personnalisables<\/li>\n<li>Limites d&rsquo;alarme haute et basse programmables avec indicateurs visuels \u00e0 LED<\/li>\n<li>Extraction et analyse des donn\u00e9es<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ec501d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ec501d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-32d4b1a\" data-id=\"32d4b1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d4f911 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8d4f911\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/www.hannamaroc.com\/waterproof-thermologger-hi148-1-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER HI148-1<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6e57aa6\" data-id=\"6e57aa6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1f35ee elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b1f35ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/www.hannamaroc.com\/enregistreur-de-temperature-hi148-2-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER HI148-2<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-0003b0b\" data-id=\"0003b0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad308b0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ad308b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/www.hannamaroc.com\/enregistreur-de-temperature-hi148-3-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER HI148-3<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f643d73\" data-id=\"f643d73\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-582bbbf elementor-align-center elementor-widget elementor-widget-button\" data-id=\"582bbbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/www.hannamaroc.com\/enregistreur-de-temperature-hi148-4-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER HI148-4<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7acf4d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7acf4d4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c432c9c\" data-id=\"c432c9c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93bfe85 elementor-widget elementor-widget-text-editor\" data-id=\"93bfe85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tWhat the producers are targeting is the optimal number of formed flower buds\n(luxm\u00e8tre) et il faut suffisamment de lumi\u00e8re pour que les plantes (journ\u00e9e longue) se d\u00e9veloppent v\u00e9g\u00e9tativement et initient la floraison (journ\u00e9e courte) en att\u00e9nuant avec le contr\u00f4le de la luminosit\u00e9.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-130b20a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"130b20a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-51b223c\" data-id=\"51b223c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-046f632 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"046f632\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-62dd10e\" data-id=\"62dd10e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab9b5fd elementor-widget elementor-widget-heading\" data-id=\"ab9b5fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La lumi\u00e8re est importante<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7eca5f0 elementor-widget elementor-widget-text-editor\" data-id=\"7eca5f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLes chrysanth\u00e8mes ont besoin de beaucoup de lumi\u00e8re pour cro\u00eetre et se d\u00e9velopper.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fe4997 elementor-widget elementor-widget-text-editor\" data-id=\"6fe4997\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLa qualit\u00e9 de la lumi\u00e8re est tr\u00e8s importante en agriculture. Trop peu de lumi\u00e8re (ou d&rsquo;intensit\u00e9 lumineuse) affecte la quantit\u00e9 et la qualit\u00e9 des performances des cultures.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1b6216 elementor-widget elementor-widget-text-editor\" data-id=\"f1b6216\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tEnviron 1,1 Klx pendant 12 heures par jour sont n\u00e9cessaires simplement pour maintenir la qualit\u00e9 de la plante pendant un an et au moins 2,1 Klx pendant 12 heures par jour sont n\u00e9cessaires pour que les plantes \u00e0 feuillage manifestent tout b\u00e9n\u00e9fice de la fertilisation.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c93eaac elementor-widget elementor-widget-text-editor\" data-id=\"c93eaac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tBien que le manque de lumi\u00e8re suffisante entra\u00eene une mauvaise croissance des plantes, trop de lumi\u00e8re peut \u00e9galement \u00eatre nocive. Les plantes d&rsquo;ombre ne peuvent pas tol\u00e9rer des niveaux de lumi\u00e8re excessivement \u00e9lev\u00e9s. Lorsqu&rsquo;une plante re\u00e7oit trop de lumi\u00e8re directe, les feuilles blanchissent ou s&rsquo;\u00e9bouillantent, parfois en train de mourir. Cela se produit souvent apr\u00e8s avoir d\u00e9plac\u00e9 une plante \u00e0 l&rsquo;ext\u00e9rieur \u00e0 la lumi\u00e8re directe. Tout changement d&rsquo;intensit\u00e9 lumineuse doit \u00eatre progressif.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-623f8ce\" data-id=\"623f8ce\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e870a6 elementor-widget elementor-widget-image\" data-id=\"3e870a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"379\" height=\"600\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-5-379x600.jpg\" class=\"attachment-large size-large wp-image-174659\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-5-379x600.jpg 379w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-5-189x300.jpg 189w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-5.jpg 469w\" sizes=\"(max-width: 379px) 100vw, 379px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-852a880 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"852a880\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-95ab530\" data-id=\"95ab530\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ddc551 elementor-widget elementor-widget-heading\" data-id=\"9ddc551\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HI97500<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5718d8b elementor-widget elementor-widget-text-editor\" data-id=\"5718d8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong>Luxm\u00e8tre portatif<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-32405bf\" data-id=\"32405bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54d090c elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54d090c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-79661e5\" data-id=\"79661e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f40939b elementor-widget elementor-widget-text-editor\" data-id=\"f40939b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>HI97500 est un luxm\u00e8tre portable con\u00e7u pour la simplicit\u00e9 d&rsquo;utilisation lors de la prise de mesures rapides de la lumi\u00e8re.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34a0606 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"34a0606\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/www.hannamaroc.com\/portable-lux-meter-hi-97500-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3550e6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f3550e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8c05e6d\" data-id=\"8c05e6d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8859e02 elementor-widget elementor-widget-image\" data-id=\"8859e02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"455\" height=\"455\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI97500.jpg\" class=\"attachment-large size-large wp-image-174668\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI97500.jpg 455w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI97500-300x300.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/HI97500-150x150.jpg 150w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-112e486 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"112e486\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e44754\" data-id=\"1e44754\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fad87be elementor-widget elementor-widget-text-editor\" data-id=\"fad87be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tAutomatisation et contr\u00f4le de l&rsquo;irrigation\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d5a93cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d5a93cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d78974\" data-id=\"2d78974\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4beb356 elementor-widget elementor-widget-text-editor\" data-id=\"4beb356\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDans la production de chrysanth\u00e8mes, il est essentiel d&rsquo;\u00e9tablir la fr\u00e9quence d&rsquo;arrosage afin que la plante ne subisse pas d&rsquo;\u00e9touffement des racines et de stress hydrique. Si les rapports entre les cycles d&rsquo;irrigation appliqu\u00e9s et les cycles de nutriments ne sont pas correctement appliqu\u00e9s, d&rsquo;\u00e9normes pertes de rendement pourraient se produire.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63a6704 elementor-widget elementor-widget-text-editor\" data-id=\"63a6704\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tAvec une irrigation appropri\u00e9e, la qualit\u00e9 et la quantit\u00e9 de chrysanth\u00e8mes peuvent \u00eatre consid\u00e9rablement am\u00e9lior\u00e9es.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f75b231 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f75b231\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dc8e355\" data-id=\"dc8e355\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8cab934 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"8cab934\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:60}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2020\/03\/137.-fertilization_system_HANNA_instruments-600x300-1.jpg\" class=\"attachment-large size-large wp-image-173359\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2020\/03\/137.-fertilization_system_HANNA_instruments-600x300-1.jpg 600w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2020\/03\/137.-fertilization_system_HANNA_instruments-600x300-1-300x150.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e2b2d76 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e2b2d76\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c8992fe\" data-id=\"c8992fe\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2ef55f elementor-widget elementor-widget-heading\" data-id=\"d2ef55f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Irrigation Correcte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9cd2836\" data-id=\"9cd2836\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88fc8f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88fc8f4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9464977\" data-id=\"9464977\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f23ee6 elementor-widget elementor-widget-text-editor\" data-id=\"2f23ee6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tCe n&rsquo;est pas un processus simple : la quantit\u00e9 d&rsquo;eau doit \u00eatre suffisante pour les plantes de Chrysanth\u00e8me, sinon la photosynth\u00e8se et la croissance globale sont entrav\u00e9es. Cependant, si la quantit\u00e9 d&rsquo;eau est plus que n\u00e9cessaire, la croissance des plantes peut devenir excessive, produisant un produit haut, plus mou et\/ou endommag\u00e9.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89047c6 elementor-widget elementor-widget-text-editor\" data-id=\"89047c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tNous concevons et fabriquons pour nos clients un syst\u00e8me complet de ferti-irrigation pr\u00eat \u00e0 installer.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df90bb2 elementor-widget elementor-widget-text-editor\" data-id=\"df90bb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDans un premier temps, nous recueillons les informations et demandes de l&rsquo;agronome pour cr\u00e9er un syst\u00e8me qui correspond aux besoins r\u00e9els du client. Par la suite, nous analysons les infrastructures existantes pour pouvoir interfacer nos syst\u00e8mes avec le luminaire d\u00e9j\u00e0 install\u00e9.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f09c2b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f09c2b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ed2866e\" data-id=\"ed2866e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-343f120 elementor-widget elementor-widget-text-editor\" data-id=\"343f120\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tEnfin, nous produisons le syst\u00e8me sur mesure et proc\u00e9dons \u00e0 l&rsquo;installation, \u00e0 la mise en service et \u00e0 la formation du personnel responsable.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8051a1 elementor-widget elementor-widget-text-editor\" data-id=\"c8051a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tNos syst\u00e8mes de ferti-irrigation ont de multiples applications:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73a3649 elementor-widget elementor-widget-text-editor\" data-id=\"73a3649\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Agriculture en plein air<\/li>\n<li>Culture int\u00e9rieure (du sol)<\/li>\n<li>Hydroponiques<\/li>\n<li>A\u00e9roponique<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-59bdc2e\" data-id=\"59bdc2e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ee305e elementor-widget elementor-widget-image\" data-id=\"9ee305e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"471\" height=\"329\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-7.jpg\" class=\"attachment-large size-large wp-image-174698\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-7.jpg 471w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-7-300x210.jpg 300w\" sizes=\"(max-width: 471px) 100vw, 471px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1640e98 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1640e98\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64f098b\" data-id=\"64f098b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b074dd5 elementor-widget elementor-widget-text-editor\" data-id=\"b074dd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tNotre syst\u00e8me de fertigation int\u00e8gre l&rsquo;\u00e9quipement de traitement Hanna Instruments avec des produits industriels de haute qualit\u00e9 pour cr\u00e9er deux types de syst\u00e8mes:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4db73b elementor-widget elementor-widget-text-editor\" data-id=\"f4db73b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Injection directe de nutriments<\/li>\n<li>Cuve de m\u00e9lange<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20ae5ea elementor-widget elementor-widget-text-editor\" data-id=\"20ae5ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tSi un probl\u00e8me de contr\u00f4le du pH ou de la conductivit\u00e9 survient, le programme g\u00e9n\u00e8re une alarme pour informer l&rsquo;utilisateur. Toutes les op\u00e9rations des deux processus de contr\u00f4le sont stock\u00e9es dans la m\u00e9moire.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9fc154e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9fc154e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17c2d59\" data-id=\"17c2d59\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a4a7df elementor-widget elementor-widget-text-editor\" data-id=\"4a4a7df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLe contr\u00f4leur de fertirrigation effectue toutes les op\u00e9rations n\u00e9cessaires, la surveillance, le contr\u00f4le des processus d&rsquo;irrigation et de fertilisation. Ces op\u00e9rations sont men\u00e9es en continu tout au long de la journ\u00e9e, du mois et de l&rsquo;ann\u00e9e.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e00163c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e00163c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5ef6af\" data-id=\"e5ef6af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13ecc82 elementor-widget elementor-widget-text-editor\" data-id=\"13ecc82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tPour utiliser et g\u00e9rer correctement le syst\u00e8me, toutes les valeurs de contr\u00f4le n\u00e9cessaires doivent \u00eatre d\u00e9finies (mode de configuration). Pendant les op\u00e9rations de surveillance (mode consultation), l&rsquo;utilisateur peut obtenir des informations sur le fonctionnement du syst\u00e8me et du processus d&rsquo;irrigation. De plus, il est possible d&rsquo;acc\u00e9der \u00e0 l&rsquo;historique de toutes les op\u00e9rations des jours en cours et pr\u00e9c\u00e9dents.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ead4ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ead4ac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6e74334\" data-id=\"6e74334\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-da70a41 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da70a41\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-788b88e\" data-id=\"788b88e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a78fc60 elementor-widget elementor-widget-heading\" data-id=\"a78fc60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conseils pour cultiver avec succ\u00e8s : <\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ceaced elementor-widget elementor-widget-text-editor\" data-id=\"6ceaced\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Gardez un journal de vos donn\u00e9es<\/li>\n<li>Gardez les r\u00e9sultats sur les goutteurs en ligne avec les valeurs du contr\u00f4leur du syst\u00e8me d&rsquo;irrigation<\/li>\n<li>\u00c9talonnez les pH-m\u00e8tres et EC portables chaque semaine<\/li>\n<li>\u00c9talonnez les capteurs de pH et d&rsquo;EC sur l&rsquo;unit\u00e9 de fertigation tous les mois<\/li>\n<li>Gardez les \u00e9lectrodes, le syst\u00e8me de fertigation et les r\u00e9servoirs d&rsquo;engrais propres pour \u00e9viter les d\u00e9p\u00f4ts<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2d2866a\" data-id=\"2d2866a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-652aba4 elementor-widget elementor-widget-image\" data-id=\"652aba4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"572\" height=\"380\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-8-Cvet.jpg\" class=\"attachment-large size-large wp-image-174713\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-8-Cvet.jpg 572w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Slika-8-Cvet-300x199.jpg 300w\" sizes=\"(max-width: 572px) 100vw, 572px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10bbf30 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10bbf30\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9de6ed6\" data-id=\"9de6ed6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c835e49 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c835e49\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f3182f5\" data-id=\"f3182f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b153d6 elementor-widget elementor-widget-text-editor\" data-id=\"8b153d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Auteur<\/strong>:<br \/>\nSa\u0161a Perica, struc.spec.ing.agr.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e8cb052\" data-id=\"e8cb052\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-57e1e78 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"57e1e78\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-14d4c67\" data-id=\"14d4c67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81e49d8 elementor-widget elementor-widget-text-editor\" data-id=\"81e49d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Source<\/strong>:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bf9b7d elementor-widget elementor-widget-text-editor\" data-id=\"7bf9b7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.savjetodavna.hr\/2017\/10\/18\/uputa-proizvodacima-krizantema-18-10-2017\/\">https:\/\/www.savjetodavna.hr\/2017\/10\/18\/uputa-proizvodacima-krizantema-18-10-2017\/<\/a><br \/>\n<br \/>\n<a href=\"https:\/\/www.savjetodavna.hr\/2009\/09\/03\/uzgoj-multiflora-krizantema-u-posudama\/\">https:\/\/www.savjetodavna.hr\/2009\/09\/03\/uzgoj-multiflora-krizantema-u-posudama\/<\/a><br \/>\n<br \/>\n<a href=\"https:\/\/hrcak.srce.hr\/file\/242265\">https:\/\/hrcak.srce.hr\/file\/242265<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-96d508d\" data-id=\"96d508d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Les chrysanth\u00e8mes sont les reines de l&rsquo;automne et la d\u00e9coration de tous les jardins. Les [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":174474,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[388],"tags":[],"class_list":["post-175152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agriculture-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Production de chrysanth\u00e8mes \u2013 pr\u00e9paration \u00e0 la transplantation - Hanna Instruments Maroc<\/title>\n<meta name=\"description\" content=\"Les chrysanth\u00e8mes en tant que fleurs qui ornent les jardins jusqu&#039;\u00e0 la fin de l&#039;automne en Croatie et dans les environs, ont le plus souvent un lien en tant que fleurs port\u00e9es au cimeti\u00e8re alors que dans le reste du monde les chrysanth\u00e8mes n&#039;ont pas un tel statut.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Production de chrysanth\u00e8mes \u2013 pr\u00e9paration \u00e0 la transplantation - Hanna Instruments Maroc\" \/>\n<meta property=\"og:description\" content=\"Les chrysanth\u00e8mes en tant que fleurs qui ornent les jardins jusqu&#039;\u00e0 la fin de l&#039;automne en Croatie et dans les environs, ont le plus souvent un lien en tant que fleurs port\u00e9es au cimeti\u00e8re alors que dans le reste du monde les chrysanth\u00e8mes n&#039;ont pas un tel statut.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/\" \/>\n<meta property=\"og:site_name\" content=\"Hanna Instruments Maroc\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-04T08:36:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-10T09:45:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Cover-1920x1220-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"976\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Milan Petrovi\u0107\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Milan Petrovi\u0107\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/production-de-chrysanthemes-preparation-a-la-transplantation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/production-de-chrysanthemes-preparation-a-la-transplantation\\\/\"},\"author\":{\"name\":\"Milan Petrovi\u0107\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/person\\\/6872d7596a0a8c85e08ebf8440a39296\"},\"headline\":\"Production de chrysanth\u00e8mes \u2013 pr\u00e9paration \u00e0 la transplantation\",\"datePublished\":\"2022-07-04T08:36:02+00:00\",\"dateModified\":\"2022-10-10T09:45:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/production-de-chrysanthemes-preparation-a-la-transplantation\\\/\"},\"wordCount\":2394,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/production-de-chrysanthemes-preparation-a-la-transplantation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Cover-1920x1220-1.jpg\",\"articleSection\":[\"Agriculture\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/production-de-chrysanthemes-preparation-a-la-transplantation\\\/\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/production-de-chrysanthemes-preparation-a-la-transplantation\\\/\",\"name\":\"Production de chrysanth\u00e8mes \u2013 pr\u00e9paration \u00e0 la transplantation - Hanna Instruments Maroc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/production-de-chrysanthemes-preparation-a-la-transplantation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/production-de-chrysanthemes-preparation-a-la-transplantation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Cover-1920x1220-1.jpg\",\"datePublished\":\"2022-07-04T08:36:02+00:00\",\"dateModified\":\"2022-10-10T09:45:34+00:00\",\"description\":\"Les chrysanth\u00e8mes en tant que fleurs qui ornent les jardins jusqu'\u00e0 la fin de l'automne en Croatie et dans les environs, ont le plus souvent un lien en tant que fleurs port\u00e9es au cimeti\u00e8re alors que dans le reste du monde les chrysanth\u00e8mes n'ont pas un tel statut.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/production-de-chrysanthemes-preparation-a-la-transplantation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/production-de-chrysanthemes-preparation-a-la-transplantation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/production-de-chrysanthemes-preparation-a-la-transplantation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Cover-1920x1220-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Cover-1920x1220-1.jpg\",\"width\":1536,\"height\":976},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/production-de-chrysanthemes-preparation-a-la-transplantation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog home\",\"item\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Production de chrysanth\u00e8mes \u2013 pr\u00e9paration \u00e0 la transplantation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\",\"name\":\"Hanna Instruments Africa\",\"description\":\"pH M\u00e8tres, Photom\u00e8tres, Titrateurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\",\"name\":\"Hanna Instruments\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/hs-logo.png\",\"contentUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/hs-logo.png\",\"width\":733,\"height\":225,\"caption\":\"Hanna Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/person\\\/6872d7596a0a8c85e08ebf8440a39296\",\"name\":\"Milan Petrovi\u0107\",\"sameAs\":[\"http:\\\/\\\/blog.hannaservice.eu\"],\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/author\\\/mpetrovic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Production de chrysanth\u00e8mes \u2013 pr\u00e9paration \u00e0 la transplantation - Hanna Instruments Maroc","description":"Les chrysanth\u00e8mes en tant que fleurs qui ornent les jardins jusqu'\u00e0 la fin de l'automne en Croatie et dans les environs, ont le plus souvent un lien en tant que fleurs port\u00e9es au cimeti\u00e8re alors que dans le reste du monde les chrysanth\u00e8mes n'ont pas un tel statut.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/","og_locale":"fr_FR","og_type":"article","og_title":"Production de chrysanth\u00e8mes \u2013 pr\u00e9paration \u00e0 la transplantation - Hanna Instruments Maroc","og_description":"Les chrysanth\u00e8mes en tant que fleurs qui ornent les jardins jusqu'\u00e0 la fin de l'automne en Croatie et dans les environs, ont le plus souvent un lien en tant que fleurs port\u00e9es au cimeti\u00e8re alors que dans le reste du monde les chrysanth\u00e8mes n'ont pas un tel statut.","og_url":"https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/","og_site_name":"Hanna Instruments Maroc","article_published_time":"2022-07-04T08:36:02+00:00","article_modified_time":"2022-10-10T09:45:34+00:00","og_image":[{"width":1536,"height":976,"url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Cover-1920x1220-1.jpg","type":"image\/jpeg"}],"author":"Milan Petrovi\u0107","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Milan Petrovi\u0107","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/#article","isPartOf":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/"},"author":{"name":"Milan Petrovi\u0107","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/person\/6872d7596a0a8c85e08ebf8440a39296"},"headline":"Production de chrysanth\u00e8mes \u2013 pr\u00e9paration \u00e0 la transplantation","datePublished":"2022-07-04T08:36:02+00:00","dateModified":"2022-10-10T09:45:34+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/"},"wordCount":2394,"publisher":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Cover-1920x1220-1.jpg","articleSection":["Agriculture"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/","url":"https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/","name":"Production de chrysanth\u00e8mes \u2013 pr\u00e9paration \u00e0 la transplantation - Hanna Instruments Maroc","isPartOf":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/#primaryimage"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Cover-1920x1220-1.jpg","datePublished":"2022-07-04T08:36:02+00:00","dateModified":"2022-10-10T09:45:34+00:00","description":"Les chrysanth\u00e8mes en tant que fleurs qui ornent les jardins jusqu'\u00e0 la fin de l'automne en Croatie et dans les environs, ont le plus souvent un lien en tant que fleurs port\u00e9es au cimeti\u00e8re alors que dans le reste du monde les chrysanth\u00e8mes n'ont pas un tel statut.","breadcrumb":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/#primaryimage","url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Cover-1920x1220-1.jpg","contentUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/07\/Cover-1920x1220-1.jpg","width":1536,"height":976},{"@type":"BreadcrumbList","@id":"https:\/\/blog.hannaservice.eu\/fr\/production-de-chrysanthemes-preparation-a-la-transplantation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog home","item":"https:\/\/blog.hannaservice.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Production de chrysanth\u00e8mes \u2013 pr\u00e9paration \u00e0 la transplantation"}]},{"@type":"WebSite","@id":"https:\/\/blog.hannaservice.eu\/fr\/#website","url":"https:\/\/blog.hannaservice.eu\/fr\/","name":"Hanna Instruments Africa","description":"pH M\u00e8tres, Photom\u00e8tres, Titrateurs","publisher":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.hannaservice.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization","name":"Hanna Instruments","url":"https:\/\/blog.hannaservice.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/01\/hs-logo.png","contentUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/01\/hs-logo.png","width":733,"height":225,"caption":"Hanna Instruments"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/person\/6872d7596a0a8c85e08ebf8440a39296","name":"Milan Petrovi\u0107","sameAs":["https:\/\/blog.hannaservice.eu"],"url":"https:\/\/blog.hannaservice.eu\/fr\/author\/mpetrovic\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/175152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/comments?post=175152"}],"version-history":[{"count":38,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/175152\/revisions"}],"predecessor-version":[{"id":189408,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/175152\/revisions\/189408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/media\/174474"}],"wp:attachment":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/media?parent=175152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/categories?post=175152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/tags?post=175152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}