{"id":191654,"date":"2022-10-19T10:49:33","date_gmt":"2022-10-19T10:49:33","guid":{"rendered":"https:\/\/blog.hannaservice.eu\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/"},"modified":"2022-12-15T13:41:04","modified_gmt":"2022-12-15T13:41:04","slug":"neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510","status":"publish","type":"post","link":"https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/","title":{"rendered":"Neutralisation du pH des effluents d&rsquo;eaux us\u00e9es : Automatisation avec le contr\u00f4leur de processus universel HI510"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"191654\" class=\"elementor elementor-191654 elementor-191232\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c105b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c105b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-990b512\" data-id=\"990b512\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb6e40e elementor-widget elementor-widget-image\" data-id=\"fb6e40e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"411\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Montaza-sa-elektrodama-i-Kontrolerom-600x411.jpg\" class=\"attachment-large size-large wp-image-191244\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Montaza-sa-elektrodama-i-Kontrolerom-600x411.jpg 600w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Montaza-sa-elektrodama-i-Kontrolerom-300x206.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Montaza-sa-elektrodama-i-Kontrolerom-768x526.jpg 768w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Montaza-sa-elektrodama-i-Kontrolerom.jpg 1026w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-03e911f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"03e911f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-86fc085\" data-id=\"86fc085\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1a29ca elementor-widget elementor-widget-heading\" data-id=\"d1a29ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HI510<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea34a77 elementor-widget elementor-widget-text-editor\" data-id=\"ea34a77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tContr\u00f4leur de processus universel\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb2fe72 elementor-widget elementor-widget-text-editor\" data-id=\"bb2fe72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tpH\/EC\/ORP\/Temp\u00e9rature\/OD\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-03bc71e\" data-id=\"03bc71e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7d1109 elementor-widget elementor-widget-image\" data-id=\"f7d1109\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"488\" height=\"144\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Hanna-Logo.jpg\" class=\"attachment-large size-large wp-image-191252\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Hanna-Logo.jpg 488w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Hanna-Logo-300x89.jpg 300w\" sizes=\"(max-width: 488px) 100vw, 488px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6a58df elementor-reverse-mobile elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a6a58df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-11fe4bd\" data-id=\"11fe4bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61dbe3a elementor-widget elementor-widget-text-editor\" data-id=\"61dbe3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLe traitement de l&rsquo;eau peut \u00eatre effectu\u00e9 dans de nombreuses applications diff\u00e9rentes et g\u00e9n\u00e9ralement toutes les eaux de proc\u00e9d\u00e9 doivent \u00eatre trait\u00e9es, qu&rsquo;elles entrent ou sortent du proc\u00e9d\u00e9. \nL&rsquo;eau qui entre est souvent trait\u00e9e et neutralis\u00e9e afin de stabiliser le pH et d&rsquo;\u00e9viter la corrosion des \u00e9quipements. \n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd98dd9 elementor-widget elementor-widget-text-editor\" data-id=\"bd98dd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLes eaux de sortie sont trait\u00e9es afin d&rsquo;\u00e9viter toute contamination et tout effet n\u00e9faste sur les aquif\u00e8res naturels. <strong>La neutralisation du pH des eaux us\u00e9es<\/strong> est une \u00e9tape critique dans la plupart des processus de traitement des eaux us\u00e9es industrielles. Il existe une multitude d&rsquo;exigences r\u00e9glementaires concernant le rejet des eaux us\u00e9es.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f817ae1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f817ae1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ecd7f66\" data-id=\"ecd7f66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86038fa elementor-widget elementor-widget-image\" data-id=\"86038fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"485\" height=\"451\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Slika-2-11.jpg\" class=\"attachment-large size-large wp-image-191259\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Slika-2-11.jpg 485w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Slika-2-11-300x279.jpg 300w\" sizes=\"(max-width: 485px) 100vw, 485px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14e29e5 elementor-reverse-mobile elementor-hidden-desktop elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14e29e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f1f6f14\" data-id=\"f1f6f14\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbda4a7 elementor-widget elementor-widget-text-editor\" data-id=\"dbda4a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLe traitement de l&rsquo;eau peut \u00eatre effectu\u00e9 dans de nombreuses applications diff\u00e9rentes et g\u00e9n\u00e9ralement toutes les eaux de proc\u00e9d\u00e9 doivent \u00eatre trait\u00e9es, qu&rsquo;elles entrent ou sortent du proc\u00e9d\u00e9. \nL&rsquo;eau qui entre est souvent trait\u00e9e et neutralis\u00e9e afin de stabiliser le pH et d&rsquo;\u00e9viter la corrosion des \u00e9quipements. \n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-540e24f elementor-widget elementor-widget-text-editor\" data-id=\"540e24f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Les eaux de sortie sont trait\u00e9es afin d&rsquo;\u00e9viter toute contamination et tout effet n\u00e9faste sur les aquif\u00e8res naturels. <strong>La neutralisation du pH des eaux us\u00e9es<\/strong> est une \u00e9tape critique dans la plupart des processus de traitement des eaux us\u00e9es industrielles. Il existe une multitude d&rsquo;exigences r\u00e9glementaires concernant le rejet des eaux us\u00e9es.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3efaaf6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3efaaf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ef595d0\" data-id=\"ef595d0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a9bbcdf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9bbcdf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-256fe36\" data-id=\"256fe36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a330945 elementor-widget elementor-widget-text-editor\" data-id=\"a330945\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLe but de la neutralisation est de modifier les eaux us\u00e9es acides \u00e0 un niveau de pH neutre ou cible avant rejet. Toute entreprise qui rejette dans les \u00e9gouts, les lacs, les ruisseaux ou d&rsquo;autres eaux de surface est tenue de neutraliser cet effluent avant de permettre son rejet ou son traitement ult\u00e9rieur dans des proc\u00e9d\u00e9s biologiques, tels que les boues ana\u00e9robies ou activ\u00e9es. Dans de nombreux cas, l&rsquo;enregistrement du pH du rejet est \u00e9galement n\u00e9cessaire.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26991bf elementor-widget elementor-widget-text-editor\" data-id=\"26991bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tProduits chimiques utilis\u00e9s pour neutraliser les eaux us\u00e9es\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbbad83 elementor-widget elementor-widget-text-editor\" data-id=\"fbbad83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLes produits chimiques les plus couramment utilis\u00e9s comprennent:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f4340a elementor-widget elementor-widget-text-editor\" data-id=\"8f4340a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>hydroxyde de sodium (soude caustique) et<\/li>\n<li>hydroxyde de calcium (chaux)<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-da9dcd2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da9dcd2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6123eda\" data-id=\"6123eda\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4032ddf elementor-widget elementor-widget-text-editor\" data-id=\"4032ddf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tCependant, ces compos\u00e9s sont r\u00e9actifs et peuvent provoquer des niveaux de pH \u00e9lev\u00e9s s&rsquo;ils ne sont pas correctement contr\u00f4l\u00e9s.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39e392e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39e392e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a51e44\" data-id=\"8a51e44\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-914107f elementor-widget elementor-widget-image\" data-id=\"914107f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"73\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/pH-Skala-600x73.jpg\" class=\"attachment-large size-large wp-image-191272\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/pH-Skala-600x73.jpg 600w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/pH-Skala-300x36.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/pH-Skala-768x93.jpg 768w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/pH-Skala.jpg 930w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5947f7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5947f7c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ef0e419\" data-id=\"ef0e419\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0852cb7 elementor-widget elementor-widget-heading\" data-id=\"0852cb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ACIDE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-221bb6e\" data-id=\"221bb6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abca30c elementor-widget elementor-widget-heading\" data-id=\"abca30c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NEUTRE <\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5eab002\" data-id=\"5eab002\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bff772 elementor-widget elementor-widget-heading\" data-id=\"2bff772\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DE BASE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28b30a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28b30a2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4374278\" data-id=\"4374278\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80aa85d elementor-widget elementor-widget-text-editor\" data-id=\"80aa85d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tSyst\u00e8mes de neutralisation du pH\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6062ccc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6062ccc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-335afb8\" data-id=\"335afb8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8073f5 elementor-widget elementor-widget-text-editor\" data-id=\"f8073f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDe nombreuses usines de traitement des eaux us\u00e9es n\u00e9cessitent un syst\u00e8me qui automatise la surveillance et le contr\u00f4le du pH dans l&rsquo;effluent par addition de produits chimiques.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a65cf4a elementor-widget elementor-widget-text-editor\" data-id=\"a65cf4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDans un syst\u00e8me typique, l&rsquo;effluent s&rsquo;\u00e9coule dans un r\u00e9servoir de r\u00e9tention o\u00f9 un capteur de pH mesure le pH des d\u00e9chets. Le contr\u00f4leur a un point de consigne de pH cibl\u00e9 pour l&rsquo;effluent et les d\u00e9chets doivent \u00eatre test\u00e9s pour \u00eatre conformes aux valeurs n\u00e9cessaires. Si les d\u00e9chets ne sont pas conformes \u00e0 cet objectif, des pompes sont utilis\u00e9es pour injecter des solutions alcalines ou acides afin d&rsquo;\u00e9quilibrer l&rsquo;effluent au bon niveau cibl\u00e9. La solution doit \u00eatre m\u00e9lang\u00e9e en continu dans un r\u00e9servoir de m\u00e9lange ou avec les agitateurs, pour assurer une bonne homog\u00e9n\u00e9isation et permettre au capteur de pH de prendre une mesure repr\u00e9sentative, ainsi que d&rsquo;assurer un bon m\u00e9lange entre l&rsquo;effluent et les produits chimiques ajout\u00e9s qui peuvent \u00eatre ajout\u00e9s pour \u00e9quilibrer le pH.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9be243a elementor-widget elementor-widget-text-editor\" data-id=\"9be243a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tUne fois la neutralisation termin\u00e9e et l&rsquo;effluent \u00e9quilibr\u00e9 \u00e0 un niveau de pH acceptable, il peut \u00eatre jet\u00e9 aux ordures.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1162c70 elementor-widget elementor-widget-text-editor\" data-id=\"1162c70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tAu point de d\u00e9charge de l&rsquo;effluent, un capteur de pH suppl\u00e9mentaire peut prendre une lecture de la valeur de sortie et enregistrer les donn\u00e9es.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3c1d4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3c1d4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cb1a4f3\" data-id=\"cb1a4f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d1ebc9 elementor-widget elementor-widget-image\" data-id=\"0d1ebc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"404\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Grafikon-Infographic-600x404.jpg\" class=\"attachment-large size-large wp-image-191282\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Grafikon-Infographic-600x404.jpg 600w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Grafikon-Infographic-300x202.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Grafikon-Infographic-768x517.jpg 768w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Grafikon-Infographic.jpg 910w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ad1997 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ad1997\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13707b6\" data-id=\"13707b6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68b46be elementor-widget elementor-widget-text-editor\" data-id=\"68b46be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLe traitement peut \u00eatre effectu\u00e9 de mani\u00e8re simple en ajoutant un contr\u00f4leur de pH au contr\u00f4le du processus et en automatisant l&rsquo;ajout d&rsquo;acide ou de base afin d&rsquo;obtenir la valeur de consigne du pH cibl\u00e9.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56939a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56939a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-715643b\" data-id=\"715643b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f85e65b elementor-widget elementor-widget-text-editor\" data-id=\"f85e65b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tHI510 est un contr\u00f4leur de processus universel avanc\u00e9 qui peut \u00eatre configur\u00e9 pour de nombreuses applications n\u00e9cessitant la surveillance et\/ou le contr\u00f4le des param\u00e8tres de processus. Il dispose d&rsquo;une entr\u00e9e de sonde num\u00e9rique qui d\u00e9tectera et mettra \u00e0 jour automatiquement le contr\u00f4leur avec le param\u00e8tre qu&rsquo;il mesure.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e2d25e elementor-widget elementor-widget-text-editor\" data-id=\"7e2d25e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLe HI510 offre des options de montage <strong>mural, sur tuyau et sur panneau.<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db2e356 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db2e356\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3fe1973\" data-id=\"3fe1973\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ff7c41 elementor-widget elementor-widget-image\" data-id=\"9ff7c41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"248\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Wall-Mounth.jpg\" class=\"attachment-large size-large wp-image-191289\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6a2a680\" data-id=\"6a2a680\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9241a1c elementor-widget elementor-widget-image\" data-id=\"9241a1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"248\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Pipe-Mounth.jpg\" class=\"attachment-large size-large wp-image-191299\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-43b7bfe\" data-id=\"43b7bfe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81e9826 elementor-widget elementor-widget-image\" data-id=\"81e9826\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"248\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Panel-Mounth.jpg\" class=\"attachment-large size-large wp-image-191306\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8bce7f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8bce7f5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e23f246\" data-id=\"e23f246\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ddeb9c elementor-widget elementor-widget-text-editor\" data-id=\"8ddeb9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tHI510 est con\u00e7u pour s&rsquo;adapter aux exigences de contr\u00f4le de processus uniques d&rsquo;un utilisateur. Le contr\u00f4leur dispose d&rsquo;un grand \u00e9cran \u00e0 matrice de points r\u00e9tro\u00e9clair\u00e9 pour une visualisation facile et offre une interface intuitive pour les options de configuration.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32ca02b elementor-widget elementor-widget-text-editor\" data-id=\"32ca02b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLe contr\u00f4leur utilise des LED multicolores pour une visualisation facile de l&rsquo;\u00e9tat de l&rsquo;instrument, y compris l&rsquo;activation du relais, en mode alarme ou en \u00e9tat de maintien. Toutes les op\u00e9rations de programmation sont effectu\u00e9es via le clavier en caoutchouc vulcanis\u00e9 \u00e0 profil bas ou avec une connexion RS485 \u00e0 un PC ex\u00e9cutant le logiciel compatible Windows HI92500.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08fda76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"08fda76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-08f0546\" data-id=\"08f0546\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b79151 elementor-widget elementor-widget-image\" data-id=\"8b79151\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"498\" height=\"400\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Water-proof-slika.jpg\" class=\"attachment-large size-large wp-image-191313\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Water-proof-slika.jpg 498w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Water-proof-slika-300x241.jpg 300w\" sizes=\"(max-width: 498px) 100vw, 498px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5badc2b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5badc2b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-88b7394\" data-id=\"88b7394\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd205e3 elementor-widget elementor-widget-text-editor\" data-id=\"cd205e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Bo\u00eetier \u00e9tanche IP65 (NEMA 4X)<\/li>\n<li>Grand \u00e9cran LCD r\u00e9tro\u00e9clair\u00e9<\/li>\n<li>Indicateurs d&rsquo;\u00e9tat LED multicolores<\/li>\n<li>Alarme auditive<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-852a1ca\" data-id=\"852a1ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be76af3 elementor-widget elementor-widget-text-editor\" data-id=\"be76af3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Clavier caoutchout\u00e9 tactile<\/li>\n<li>Montage universel<\/li>\n<li>Sonde num\u00e9rique universelle Hanna<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-757cf7a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"757cf7a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1a34197\" data-id=\"1a34197\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d04fc2 elementor-widget elementor-widget-text-editor\" data-id=\"7d04fc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLe mode de contr\u00f4le peut \u00eatre configur\u00e9 pour \u00eatre:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ee8998 elementor-widget elementor-widget-text-editor\" data-id=\"7ee8998\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Allum\u00e9 \u00e9teint,<\/li>\n<li>Proportionnel ou<\/li>\n<li>types de PID.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-568cb92 elementor-widget elementor-widget-text-editor\" data-id=\"568cb92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLe mode peut \u00eatre r\u00e9gl\u00e9 sur <strong>haut ou bas.<\/strong> Le mode de contr\u00f4le \u00e9lev\u00e9 est requis si la valeur de proc\u00e9d\u00e9 est trop \u00e9lev\u00e9e et doit \u00eatre diminu\u00e9e.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8d7dab elementor-widget elementor-widget-text-editor\" data-id=\"e8d7dab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLe mode de contr\u00f4le bas est requis si la valeur de proc\u00e9d\u00e9 est trop basse et doit \u00eatre augment\u00e9e.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b3b203 elementor-widget elementor-widget-text-editor\" data-id=\"8b3b203\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tEntr\u00e9es num\u00e9riques\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25b8f35 elementor-widget elementor-widget-text-editor\" data-id=\"25b8f35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n \t<li>Deux entr\u00e9es num\u00e9riques sont disponibles pour les fonctions de d\u00e9clenchement, de nettoyage et de maintien \u00e0 distance<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4effd7 elementor-widget elementor-widget-text-editor\" data-id=\"a4effd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tSorties analogiques\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8a0672 elementor-widget elementor-widget-text-editor\" data-id=\"d8a0672\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Disponible avec jusqu&rsquo;\u00e0 quatre sorties analogiques et 5 relais utilis\u00e9s pour le contr\u00f4le et pour envoyer un signal aux enregistreurs de donn\u00e9es, PLC, SCADA et autres syst\u00e8mes de surveillance \u00e0 distance<\/li>\n<li><strong>0-20 mA ou 4-20 mA<\/strong><\/li>\n<li>\u00c9volutif dans la s\u00e9lection des valeurs de la gamme<\/li>\n<li><strong>Peut \u00eatre utilis\u00e9 pour le contr\u00f4le des pompes et des vannes<\/strong><\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26dcdf2 elementor-widget elementor-widget-text-editor\" data-id=\"26dcdf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Communications num\u00e9riques<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-082a32f elementor-widget elementor-widget-text-editor\" data-id=\"082a32f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>\n<p>L&rsquo;application PC Hanna HI92500 prend en charge la communication entre le contr\u00f4leur et un PC.<\/p>\n<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aec69ef elementor-hidden-mobile elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"aec69ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e02de70\" data-id=\"e02de70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8a65c6 elementor-widget elementor-widget-text-editor\" data-id=\"a8a65c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong>Les t\u00e2ches suivantes peuvent \u00eatre <\/strong><br>\n<strong>r\u00e9alis\u00e9 \u00e0 distance :<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e859104 elementor-widget elementor-widget-text-editor\" data-id=\"e859104\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Surveillance \u00e0 l&rsquo;aide de l&rsquo;\u00e9cran LCD virtuel (limit\u00e9 \u00e0 une seule t\u00e9l\u00e9commande dans tout le r\u00e9seau)<\/li>\n<li>Installer<\/li>\n<li>Chargement du fichier de configuration d&rsquo;installation sur un contr\u00f4leur<\/li>\n<li>Sortie num\u00e9rique RS485 pour la connectivit\u00e9 PC et autres appareils<\/li>\n<li>Connectez en s\u00e9rie jusqu&rsquo;\u00e0 32 appareils \u00e0 un syst\u00e8me de surveillance \u00e0 distance<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fd48fb elementor-widget elementor-widget-text-editor\" data-id=\"6fd48fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tpH\/EC\/DO\/ORP\/temp\u00e9rature\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3de161d elementor-widget elementor-widget-text-editor\" data-id=\"3de161d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Outre le pH, proc\u00e9d\u00e9 universel<\/strong><br \/><strong>contr\u00f4leur peut \u00eatre utilis\u00e9 pour la surveillance<\/strong><br \/><strong>de CE, O.D. et redox<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2eab24e elementor-widget elementor-widget-image\" data-id=\"2eab24e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"392\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Slika-za-BUY-NOW.jpg\" class=\"attachment-large size-large wp-image-191323\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Slika-za-BUY-NOW.jpg 336w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Slika-za-BUY-NOW-257x300.jpg 257w\" sizes=\"(max-width: 336px) 100vw, 336px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfe309a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"dfe309a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/www.hannamaroc.com\/controleur-de-processus-universel-hi510-0320-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ACHETER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c6f2f7a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c6f2f7a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40ee271\" data-id=\"40ee271\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef4e70d elementor-widget elementor-widget-text-editor\" data-id=\"ef4e70d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tSondes intelligentes industrielles compatibles avec le contr\u00f4leur de processus universel HI510\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c0cf52 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c0cf52\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e78a726\" data-id=\"e78a726\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61e445c elementor-widget elementor-widget-heading\" data-id=\"61e445c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">pH et temp\u00e9rature<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a44949e elementor-hidden-mobile\" data-id=\"a44949e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b642eae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b642eae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-08e6845\" data-id=\"08e6845\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71da11c elementor-widget elementor-widget-text-editor\" data-id=\"71da11c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>S\u00e9ries HI1006-18 et HI1016-18,<br \/>con\u00e7u pour les environnements de process \u00e0 faible conductivit\u00e9 ou basse temp\u00e9rature<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1b0d17b\" data-id=\"1b0d17b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d871f9 elementor-widget elementor-widget-image\" data-id=\"3d871f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"523\" height=\"87\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/pH-and-temperature-electrode.jpg\" class=\"attachment-large size-large wp-image-191339\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/pH-and-temperature-electrode.jpg 523w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/pH-and-temperature-electrode-300x50.jpg 300w\" sizes=\"(max-width: 523px) 100vw, 523px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ec2830 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ec2830\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-73ad316 elementor-hidden-mobile\" data-id=\"73ad316\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-913f1b4\" data-id=\"913f1b4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56b58fd elementor-widget elementor-widget-heading\" data-id=\"56b58fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Redox et temp\u00e9rature<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c912d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c912d9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3e39231\" data-id=\"3e39231\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82e857b elementor-widget elementor-widget-image\" data-id=\"82e857b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"483\" height=\"342\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Orp-and-temperature-Elektrode.jpg\" class=\"attachment-large size-large wp-image-191346\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Orp-and-temperature-Elektrode.jpg 483w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Orp-and-temperature-Elektrode-300x212.jpg 300w\" sizes=\"(max-width: 483px) 100vw, 483px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fba6ffb\" data-id=\"fba6ffb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4839afe elementor-widget elementor-widget-text-editor\" data-id=\"4839afe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tCes sondes ORP industrielles intelligentes sont utilis\u00e9es pour mesurer le rapport des esp\u00e8ces oxyd\u00e9es aux esp\u00e8ces r\u00e9duites dans le processus. Avec le Hanna Instruments HI510, ils peuvent surveiller et contr\u00f4ler les produits chimiques de d\u00e9sinfection ou suivre et contr\u00f4ler une r\u00e9action critique d&rsquo;oxydation ou de r\u00e9duction.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f15b927 elementor-widget elementor-widget-text-editor\" data-id=\"f15b927\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n \t<li>S\u00e9rie de capteurs platine HI2004-18 et HI2014-18, con\u00e7ues pour fournir la meilleure r\u00e9ponse sur une large gamme d&rsquo;applications<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7a11ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7a11ef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-87c915b\" data-id=\"87c915b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f609e32 elementor-widget elementor-widget-heading\" data-id=\"f609e32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conductivit\u00e9<br> et temp\u00e9rature<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-04d9aae elementor-hidden-mobile\" data-id=\"04d9aae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71cd37d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71cd37d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3e39d1a\" data-id=\"3e39d1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fe71a4 elementor-widget elementor-widget-text-editor\" data-id=\"6fe71a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tRecommand\u00e9e pour les applications d&rsquo;eau propre et non corrosive, la s\u00e9rie HI7630-28 peut \u00eatre \u00e9talonn\u00e9e \u00e0 l&rsquo;aide d&rsquo;un standard avec une valeur proche de la valeur de mesure.\nLa s\u00e9rie HI7630-48 fournit une mesure exceptionnellement stable sur une\nlarge plage de mesure et ne n\u00e9cessite pas d&rsquo;\u00e9talonnage fr\u00e9quent.\nLes sondes peuvent \u00eatre install\u00e9es directement en ligne, immerg\u00e9es dans un r\u00e9servoir ou une cellule \u00e0 \u00e9coulement.\nles sondes de conductivit\u00e9 conviennent \u00e0 la mesure continue de la conductivit\u00e9\net les param\u00e8tres associ\u00e9s requis dans des applications telles que le traitement de l&rsquo;eau,\nl&rsquo;eau potable, le condensat d&rsquo;eau d&rsquo;alimentation ou d&rsquo;autres applications d&rsquo;eau propre.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49e4c72 elementor-hidden-mobile elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"49e4c72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ddf99d1\" data-id=\"ddf99d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8e4501 elementor-widget elementor-widget-image\" data-id=\"b8e4501\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"539\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Conductivity-and-temperature-Elektrode.jpg\" class=\"attachment-large size-large wp-image-191356\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Conductivity-and-temperature-Elektrode.jpg 533w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Conductivity-and-temperature-Elektrode-297x300.jpg 297w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-491bdcb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"491bdcb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0f88edf elementor-hidden-mobile\" data-id=\"0f88edf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0d610a9\" data-id=\"0d610a9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-908de32 elementor-widget elementor-widget-heading\" data-id=\"908de32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Galvanique<br> Oxyg\u00e8ne Dissous<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c105e3 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c105e3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-56d54fb\" data-id=\"56d54fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6f8c91 elementor-widget elementor-widget-image\" data-id=\"b6f8c91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"600\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Galvanic-DO-Elektrode-324x600.jpg\" class=\"attachment-large size-large wp-image-191366\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Galvanic-DO-Elektrode-324x600.jpg 324w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Galvanic-DO-Elektrode-162x300.jpg 162w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Galvanic-DO-Elektrode.jpg 391w\" sizes=\"(max-width: 324px) 100vw, 324px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-afb7869\" data-id=\"afb7869\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64c644f elementor-widget elementor-widget-text-editor\" data-id=\"64c644f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLa s\u00e9rie HI7640-18 sont des sondes \u00e0 oxyg\u00e8ne de style galvanique\ncon\u00e7u pour \u00eatre utilis\u00e9 avec le contr\u00f4leur de processus universel Hanna Instruments HI510. La sonde est adapt\u00e9e \u00e0 la mesure continue de l&rsquo;oxyg\u00e8ne dissous dans l&rsquo;eau. Un capteur de temp\u00e9rature int\u00e9gr\u00e9 mesure la temp\u00e9rature de l&rsquo;eau et ajuste le signal de la sonde sur la plage de temp\u00e9rature sp\u00e9cifi\u00e9e.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26df69d elementor-widget elementor-widget-text-editor\" data-id=\"26df69d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLe r\u00e9sultat est une mesure fiable de la concentration en oxyg\u00e8ne dissous (OD) ou du pourcentage de saturation.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e22154c elementor-widget elementor-widget-text-editor\" data-id=\"e22154c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tAdapt\u00e9e aux applications de contr\u00f4le dans le traitement des eaux us\u00e9es municipales et industrielles, la sonde peut \u00eatre install\u00e9e directement en ligne, immerg\u00e9e dans un r\u00e9servoir ou dans une installation de cellule d&rsquo;\u00e9coulement.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19fda0f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19fda0f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-36a7069\" data-id=\"36a7069\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75159eb elementor-widget elementor-widget-heading\" data-id=\"75159eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Optique <br>Oxyg\u00e8ne Dissous\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-64c3a64 elementor-hidden-mobile\" data-id=\"64c3a64\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5eb4065 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5eb4065\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7dd5ba6\" data-id=\"7dd5ba6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e1cbcb elementor-widget elementor-widget-text-editor\" data-id=\"7e1cbcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLa s\u00e9rie HI7640-58 sont des sondes optiques \u00e0 oxyg\u00e8ne dissous avec\nHI764113-1 OD Smart Caps pour les mesures d&rsquo;oxyg\u00e8ne dissous.\nLorsqu&rsquo;il est associ\u00e9 au contr\u00f4leur, le syst\u00e8me fournit des mesures d&rsquo;OD pr\u00e9cises auto-compens\u00e9es pour la pression barom\u00e9trique, la salinit\u00e9 (r\u00e9gl\u00e9e manuellement) et la temp\u00e9rature.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebcbf57 elementor-widget elementor-widget-text-editor\" data-id=\"ebcbf57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tConvient aux applications de contr\u00f4le des eaux us\u00e9es municipales et industrielles\ntraitement, o\u00f9 l&rsquo;optimisation du transfert d&rsquo;oxyg\u00e8ne est un \u00e9l\u00e9ment cl\u00e9, la\nla sonde peut \u00eatre install\u00e9e directement en ligne, immerg\u00e9e dans un r\u00e9servoir ou dans un flow\nmise en place de cellule.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f4b7be elementor-widget elementor-widget-text-editor\" data-id=\"5f4b7be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Smart Cap calibr\u00e9 en usine<\/li>\n<li>Faible maintenance (pas de recharge d&rsquo;\u00e9lectrolyte ni de remplacement de membrane)<\/li>\n<li>Fiabilit\u00e9 de mesure ind\u00e9pendante du d\u00e9bit<\/li>\n<li>Temps de r\u00e9ponse r\u00e9duit<\/li>\n<li>Lectures stables m\u00eame lorsque la concentration en oxyg\u00e8ne est faible<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0142b1d\" data-id=\"0142b1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e2cdc3 elementor-widget elementor-widget-image\" data-id=\"8e2cdc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"110\" height=\"600\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Optical-dissolved-oxigen-Electrode-110x600.jpg\" class=\"attachment-large size-large wp-image-191379\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Optical-dissolved-oxigen-Electrode-110x600.jpg 110w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Optical-dissolved-oxigen-Electrode-55x300.jpg 55w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Optical-dissolved-oxigen-Electrode.jpg 121w\" sizes=\"(max-width: 110px) 100vw, 110px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f499e8d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f499e8d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-871a744\" data-id=\"871a744\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b4e07d elementor-widget elementor-widget-text-editor\" data-id=\"9b4e07d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLes sondes peuvent \u00eatre install\u00e9es directement dans le r\u00e9servoir avec des porte-\u00e9lectrodes sp\u00e9cialement con\u00e7us\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e34dc1a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e34dc1a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de7891f\" data-id=\"de7891f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ee0694 elementor-widget elementor-widget-text-editor\" data-id=\"9ee0694\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hannamaroc.com\/porte-electrodes-a-immersion-hi60501-product\" target=\"_blank\" rel=\"noopener\">HI60501<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e679b94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e679b94\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-253082b\" data-id=\"253082b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce3873b elementor-widget elementor-widget-text-editor\" data-id=\"ce3873b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLe HI60501 est un porte-\u00e9lectrode pour une installation en immersion pour r\u00e9servoirs, r\u00e9cipients, bains et canaux ouverts. Cette \u00e9lectrode est fabriqu\u00e9e en PVC robuste et peut r\u00e9sister \u00e0 la plupart des produits chimiques.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e606daa elementor-widget elementor-widget-image\" data-id=\"e606daa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"463\" height=\"414\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Tehnical-drawing-1.jpg\" class=\"attachment-large size-large wp-image-191395\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Tehnical-drawing-1.jpg 463w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Tehnical-drawing-1-300x268.jpg 300w\" sizes=\"(max-width: 463px) 100vw, 463px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d83c7df\" data-id=\"d83c7df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dac1c9 elementor-widget elementor-widget-image\" data-id=\"3dac1c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"404\" height=\"600\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Technical-drawing-2-404x600.jpg\" class=\"attachment-large size-large wp-image-191402\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Technical-drawing-2-404x600.jpg 404w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Technical-drawing-2-202x300.jpg 202w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Technical-drawing-2.jpg 444w\" sizes=\"(max-width: 404px) 100vw, 404px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a5b4e28 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a5b4e28\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f3de14\" data-id=\"7f3de14\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e71ae27 elementor-widget elementor-widget-text-editor\" data-id=\"e71ae27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tUne fois mont\u00e9 sur le r\u00e9servoir, le porte-\u00e9lectrode est un bo\u00eetier de protection robuste qui prolongera la dur\u00e9e de vie des \u00e9lectrodes. L&rsquo;\u00e9lectrode glisse dans le support et est serr\u00e9e \u00e0 la main en place. Le c\u00e2ble de l&rsquo;\u00e9lectrode passera par le support et sortira par le capuchon sur le dessus. Le c\u00e2ble est \u00e9galement blind\u00e9 \u00e0 l&rsquo;int\u00e9rieur du support pour \u00e9viter tout dommage \u00e0 l&rsquo;isolation. Le capuchon de protection est amovible pour permettre un entretien et un remplacement rapides et simples des \u00e9lectrodes.\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b99414 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7b99414\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ad6ba4d\" data-id=\"ad6ba4d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a3414b elementor-widget elementor-widget-text-editor\" data-id=\"8a3414b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong>Auteur<\/strong>:<br>\nNives Vincekovi\u0107 Budor<br>mag.ing.chem.ing\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-421826c\" data-id=\"421826c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0025638 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0025638\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-82ec0c0\" data-id=\"82ec0c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-652995c elementor-widget elementor-widget-image\" data-id=\"652995c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"252\" height=\"74\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/08\/Logo-Hanna-Inst.jpg\" class=\"attachment-large size-large wp-image-177342\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ad350f elementor-widget elementor-widget-text-editor\" data-id=\"9ad350f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Avec un excellent produit, d&rsquo;excellents r\u00e9sultats<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a20aeab\" data-id=\"a20aeab\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-683050a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"683050a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9c4034a\" data-id=\"9c4034a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a71411 elementor-widget elementor-widget-heading\" data-id=\"7a71411\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Service <\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2e46379 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e46379\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ed2d137\" data-id=\"ed2d137\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a04082c elementor-widget elementor-widget-heading\" data-id=\"a04082c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Entra\u00eenement<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8309a59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8309a59\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-433160c\" data-id=\"433160c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2480d9c elementor-widget elementor-widget-heading\" data-id=\"2480d9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rapair<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d8458d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d8458d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-868498f\" data-id=\"868498f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26ceeef elementor-widget elementor-widget-heading\" data-id=\"26ceeef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Maintenance<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>HI510 Contr\u00f4leur de processus universelpH\/EC\/ORP\/Temp\u00e9rature\/OD Le traitement de l&rsquo;eau peut \u00eatre effectu\u00e9 dans de nombreuses [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":191236,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[393,392],"tags":[],"class_list":["post-191654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eau","category-industrie-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neutralisation du pH des effluents d&#039;eaux us\u00e9es : Automatisation avec le contr\u00f4leur de processus universel HI510 - Hanna Instruments Maroc<\/title>\n<meta name=\"description\" content=\"Les eaux de sortie sont trait\u00e9es afin d&#039;\u00e9viter toute contamination et tout effet n\u00e9faste sur les aquif\u00e8res naturels. La neutralisation du pH des eaux us\u00e9es est une \u00e9tape critique dans la plupart des processus de traitement des eaux us\u00e9es industrielles. Il existe une multitude d&#039;exigences r\u00e9glementaires concernant le rejet des eaux us\u00e9es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neutralisation du pH des effluents d&#039;eaux us\u00e9es : Automatisation avec le contr\u00f4leur de processus universel HI510 - Hanna Instruments Maroc\" \/>\n<meta property=\"og:description\" content=\"Les eaux de sortie sont trait\u00e9es afin d&#039;\u00e9viter toute contamination et tout effet n\u00e9faste sur les aquif\u00e8res naturels. La neutralisation du pH des eaux us\u00e9es est une \u00e9tape critique dans la plupart des processus de traitement des eaux us\u00e9es industrielles. Il existe une multitude d&#039;exigences r\u00e9glementaires concernant le rejet des eaux us\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/\" \/>\n<meta property=\"og:site_name\" content=\"Hanna Instruments Maroc\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-19T10:49:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-15T13:41:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Cover-1920-x-1220-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"976\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Milan Petrovi\u0107\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Milan Petrovi\u0107\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\\\/\"},\"author\":{\"name\":\"Milan Petrovi\u0107\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/person\\\/6872d7596a0a8c85e08ebf8440a39296\"},\"headline\":\"Neutralisation du pH des effluents d&rsquo;eaux us\u00e9es : Automatisation avec le contr\u00f4leur de processus universel HI510\",\"datePublished\":\"2022-10-19T10:49:33+00:00\",\"dateModified\":\"2022-12-15T13:41:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\\\/\"},\"wordCount\":1876,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Cover-1920-x-1220-1.jpg\",\"articleSection\":[\"Eau\",\"Industrie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\\\/\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\\\/\",\"name\":\"Neutralisation du pH des effluents d'eaux us\u00e9es : Automatisation avec le contr\u00f4leur de processus universel HI510 - Hanna Instruments Maroc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Cover-1920-x-1220-1.jpg\",\"datePublished\":\"2022-10-19T10:49:33+00:00\",\"dateModified\":\"2022-12-15T13:41:04+00:00\",\"description\":\"Les eaux de sortie sont trait\u00e9es afin d'\u00e9viter toute contamination et tout effet n\u00e9faste sur les aquif\u00e8res naturels. La neutralisation du pH des eaux us\u00e9es est une \u00e9tape critique dans la plupart des processus de traitement des eaux us\u00e9es industrielles. Il existe une multitude d'exigences r\u00e9glementaires concernant le rejet des eaux us\u00e9es.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Cover-1920-x-1220-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Cover-1920-x-1220-1.jpg\",\"width\":1536,\"height\":976},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog home\",\"item\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neutralisation du pH des effluents d&rsquo;eaux us\u00e9es : Automatisation avec le contr\u00f4leur de processus universel HI510\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\",\"name\":\"Hanna Instruments Africa\",\"description\":\"pH M\u00e8tres, Photom\u00e8tres, Titrateurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\",\"name\":\"Hanna Instruments\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/hs-logo.png\",\"contentUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/hs-logo.png\",\"width\":733,\"height\":225,\"caption\":\"Hanna Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/person\\\/6872d7596a0a8c85e08ebf8440a39296\",\"name\":\"Milan Petrovi\u0107\",\"sameAs\":[\"http:\\\/\\\/blog.hannaservice.eu\"],\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/author\\\/mpetrovic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neutralisation du pH des effluents d'eaux us\u00e9es : Automatisation avec le contr\u00f4leur de processus universel HI510 - Hanna Instruments Maroc","description":"Les eaux de sortie sont trait\u00e9es afin d'\u00e9viter toute contamination et tout effet n\u00e9faste sur les aquif\u00e8res naturels. La neutralisation du pH des eaux us\u00e9es est une \u00e9tape critique dans la plupart des processus de traitement des eaux us\u00e9es industrielles. Il existe une multitude d'exigences r\u00e9glementaires concernant le rejet des eaux us\u00e9es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/","og_locale":"fr_FR","og_type":"article","og_title":"Neutralisation du pH des effluents d'eaux us\u00e9es : Automatisation avec le contr\u00f4leur de processus universel HI510 - Hanna Instruments Maroc","og_description":"Les eaux de sortie sont trait\u00e9es afin d'\u00e9viter toute contamination et tout effet n\u00e9faste sur les aquif\u00e8res naturels. La neutralisation du pH des eaux us\u00e9es est une \u00e9tape critique dans la plupart des processus de traitement des eaux us\u00e9es industrielles. Il existe une multitude d'exigences r\u00e9glementaires concernant le rejet des eaux us\u00e9es.","og_url":"https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/","og_site_name":"Hanna Instruments Maroc","article_published_time":"2022-10-19T10:49:33+00:00","article_modified_time":"2022-12-15T13:41:04+00:00","og_image":[{"width":1536,"height":976,"url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Cover-1920-x-1220-1.jpg","type":"image\/jpeg"}],"author":"Milan Petrovi\u0107","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Milan Petrovi\u0107","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/#article","isPartOf":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/"},"author":{"name":"Milan Petrovi\u0107","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/person\/6872d7596a0a8c85e08ebf8440a39296"},"headline":"Neutralisation du pH des effluents d&rsquo;eaux us\u00e9es : Automatisation avec le contr\u00f4leur de processus universel HI510","datePublished":"2022-10-19T10:49:33+00:00","dateModified":"2022-12-15T13:41:04+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/"},"wordCount":1876,"publisher":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Cover-1920-x-1220-1.jpg","articleSection":["Eau","Industrie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/","url":"https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/","name":"Neutralisation du pH des effluents d'eaux us\u00e9es : Automatisation avec le contr\u00f4leur de processus universel HI510 - Hanna Instruments Maroc","isPartOf":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/#primaryimage"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Cover-1920-x-1220-1.jpg","datePublished":"2022-10-19T10:49:33+00:00","dateModified":"2022-12-15T13:41:04+00:00","description":"Les eaux de sortie sont trait\u00e9es afin d'\u00e9viter toute contamination et tout effet n\u00e9faste sur les aquif\u00e8res naturels. La neutralisation du pH des eaux us\u00e9es est une \u00e9tape critique dans la plupart des processus de traitement des eaux us\u00e9es industrielles. Il existe une multitude d'exigences r\u00e9glementaires concernant le rejet des eaux us\u00e9es.","breadcrumb":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/#primaryimage","url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Cover-1920-x-1220-1.jpg","contentUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/10\/Cover-1920-x-1220-1.jpg","width":1536,"height":976},{"@type":"BreadcrumbList","@id":"https:\/\/blog.hannaservice.eu\/fr\/neutralisation-du-ph-des-effluents-deaux-usees-automatisation-avec-le-controleur-de-processus-universel-hi510\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog home","item":"https:\/\/blog.hannaservice.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Neutralisation du pH des effluents d&rsquo;eaux us\u00e9es : Automatisation avec le contr\u00f4leur de processus universel HI510"}]},{"@type":"WebSite","@id":"https:\/\/blog.hannaservice.eu\/fr\/#website","url":"https:\/\/blog.hannaservice.eu\/fr\/","name":"Hanna Instruments Africa","description":"pH M\u00e8tres, Photom\u00e8tres, Titrateurs","publisher":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.hannaservice.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization","name":"Hanna Instruments","url":"https:\/\/blog.hannaservice.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/01\/hs-logo.png","contentUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/01\/hs-logo.png","width":733,"height":225,"caption":"Hanna Instruments"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/person\/6872d7596a0a8c85e08ebf8440a39296","name":"Milan Petrovi\u0107","sameAs":["https:\/\/blog.hannaservice.eu"],"url":"https:\/\/blog.hannaservice.eu\/fr\/author\/mpetrovic\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/191654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/comments?post=191654"}],"version-history":[{"count":26,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/191654\/revisions"}],"predecessor-version":[{"id":199530,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/191654\/revisions\/199530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/media\/191236"}],"wp:attachment":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/media?parent=191654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/categories?post=191654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/tags?post=191654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}