{"id":212324,"date":"2023-07-26T14:06:13","date_gmt":"2023-07-26T14:06:13","guid":{"rendered":"https:\/\/blog.hannaservice.eu\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/"},"modified":"2023-08-16T08:08:22","modified_gmt":"2023-08-16T08:08:22","slug":"comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau","status":"publish","type":"post","link":"https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/","title":{"rendered":"Comprendre l&rsquo;importance de la DBO : mesurer les niveaux d&rsquo;oxyg\u00e8ne dans l&rsquo;eau"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"212324\" class=\"elementor elementor-212324 elementor-212156\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dfb7e7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dfb7e7c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e5a4d0\" data-id=\"4e5a4d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-124ee90 elementor-widget elementor-widget-html\" data-id=\"124ee90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<style>.entry-content p {\n    margin-bottom: 0.8em;\n    line-height: 1.6em;\n}\n\n\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f9cf874 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f9cf874\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-307881b\" data-id=\"307881b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1aee6fa\" data-id=\"1aee6fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a0fb60 elementor-widget elementor-widget-heading\" data-id=\"2a0fb60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La demande biologique en oxyg\u00e8ne (DBO) est une mesure de la quantit\u00e9 d'oxyg\u00e8ne dissous (OD) utilis\u00e9e par les micro-organismes a\u00e9robies lors de la d\u00e9composition de la mati\u00e8re organique dans l'eau.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ecd8ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ecd8ae\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-973941e\" data-id=\"973941e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7fff750 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7fff750\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-86f2bad\" data-id=\"86f2bad\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44bd017 elementor-widget elementor-widget-heading\" data-id=\"44bd017\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Importance de la DBO pour les eaux us\u00e9es<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-81e2968\" data-id=\"81e2968\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1cb366d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cb366d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e2e4042\" data-id=\"e2e4042\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c8e09b elementor-widget elementor-widget-text-editor\" data-id=\"4c8e09b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>La demande biologique en oxyg\u00e8ne (DBO) est un param\u00e8tre important dans l&rsquo;\u00e9valuation de la qualit\u00e9 de l&rsquo;eau car elle sert d&rsquo;indicateur pour d\u00e9terminer l&rsquo;impact des eaux us\u00e9es rejet\u00e9es sur l&rsquo;\u00e9cosyst\u00e8me environnant.<\/strong><\/p>\n<p>Plus la valeur de la DBO est \u00e9lev\u00e9e, plus la quantit\u00e9 de mati\u00e8re organique ou \u00ab nourriture \u00bb disponible pour les bact\u00e9ries consommatrices d&rsquo;oxyg\u00e8ne est importante. Si le taux de consommation d&rsquo;OD par les bact\u00e9ries d\u00e9passe l&rsquo;apport d&rsquo;OD provenant des plantes aquatiques, de la photosynth\u00e8se des algues ou de la diffusion \u00e0 partir de l&rsquo;air, des conditions d\u00e9favorables se produisent. L&rsquo;\u00e9puisement de l&rsquo;OD provoque un stress sur les organismes aquatiques, rendant l&rsquo;environnement impropre \u00e0 la vie. De plus, un \u00e9puisement dramatique peut conduire \u00e0 une hypoxie ou \u00e0 des environnements anoxiques.<\/p>\n<p>La DBO est \u00e9galement largement utilis\u00e9e dans le traitement des eaux us\u00e9es, o\u00f9 la d\u00e9composition des d\u00e9chets organiques par des micro-organismes est couramment utilis\u00e9e comme m\u00e9thode de traitement. Les r\u00e9glementations et les permis pour les effluents de demande biochimique en oxyg\u00e8ne varient selon les pays et les r\u00e9gions, comme le National Pollution Discharge Elimination System (NPDES) aux \u00c9tats-Unis, qui \u00e9tablit une concentration maximale autoris\u00e9e pour le rejet direct dans l&rsquo;environnement ou le rejet dans un syst\u00e8me d&rsquo;\u00e9gout municipal.<\/p>\n<p><strong>Afin d&rsquo;\u00eatre rejet\u00e9es en toute s\u00e9curit\u00e9 dans l&rsquo;environnement, les eaux trait\u00e9es doivent avoir une DBO suffisamment faible pour \u00e9viter d&rsquo;\u00e9puiser les \u00e9cosyst\u00e8mes de leur approvisionnement en oxyg\u00e8ne dissous (OD).<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d69d478 elementor-widget elementor-widget-text-editor\" data-id=\"d69d478\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Les eaux us\u00e9es brutes ont g\u00e9n\u00e9ralement une concentration d&rsquo;OD inf\u00e9rieure \u00e0 <strong>20 % ou 1-2 mg\/L,<\/strong> alors qu&rsquo;un \u00e9cosyst\u00e8me fluvial sain devrait \u00eatre proche de <strong>100 % de saturation (8-10 mg\/L).<\/strong><\/li>\n<li>Le rejet d&rsquo;eaux us\u00e9es insuffisamment trait\u00e9es peut amener les bact\u00e9ries \u00e0 consommer l&rsquo;oxyg\u00e8ne plus rapidement que les plantes aquatiques, les algues et l&rsquo;a\u00e9ration naturelle peuvent le reconstituer.<\/li>\n<li>Les faibles niveaux d&rsquo;OD qui en r\u00e9sultent peuvent stresser un \u00e9cosyst\u00e8me et avoir des effets n\u00e9fastes sur la vie aquatique tels que la mort de poissons et la perte d&rsquo;esp\u00e8ces.<\/li>\n<li>La DBO<sub>5<\/sub> est le test de contr\u00f4le le plus courant pour d\u00e9terminer la qualit\u00e9 des eaux rejet\u00e9es, mais il est tr\u00e8s lent (5 jours) et n&rsquo;offre qu&rsquo;une pr\u00e9cision limit\u00e9e.<\/li>\n<li>Lorsqu&rsquo;il s&rsquo;av\u00e8re que les eaux d\u00e9passent les seuils de conformit\u00e9, il est trop tard pour prendre des mesures correctives car elles ont d\u00e9j\u00e0 \u00e9t\u00e9 rejet\u00e9es.<\/li>\n<li>Les municipalit\u00e9s disposant de syst\u00e8mes d&rsquo;\u00e9gouts unitaires qui collectent \u00e9galement les eaux de pluie sont sujettes \u00e0 des d\u00e9bordements d&rsquo;\u00e9gouts unitaires (CSO) qui peuvent lib\u00e9rer des eaux \u00e0 forte DBO.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c98b675 elementor-widget elementor-widget-text-editor\" data-id=\"c98b675\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>La surveillance en temps r\u00e9el de la DBO devient de plus en plus populaire. La surveillance continue des mati\u00e8res organiques ouvre la porte \u00e0 de nombreuses nouvelles possibilit\u00e9s de contr\u00f4le et d&rsquo;optimisation des processus de traitement qui peuvent entra\u00eener des \u00e9conomies importantes, une meilleure qualit\u00e9 de l&rsquo;eau et une tranquillit\u00e9 d&rsquo;esprit en mati\u00e8re de conformit\u00e9.<\/p>\n<p><strong>Les applications des eaux us\u00e9es pour la mesure en ligne de la DBO comprennent :<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-207984e elementor-widget elementor-widget-text-editor\" data-id=\"207984e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Surveillance des eaux us\u00e9es<\/li>\n<li>Optimisation de la dose chimique<\/li>\n<li>Optimisation de l&rsquo;a\u00e9ration<\/li>\n<li>Optimisation de la dose de nutriments<\/li>\n<li>Gestion des rejets d&rsquo;effluents industriels<\/li>\n<li>Surveillance des pertes de produits<\/li>\n<li>Surveillance et protection avanc\u00e9es des traitements<\/li>\n<li>Optimisation de la r\u00e9utilisation de l&rsquo;eau<\/li>\n<li>Contr\u00f4le de la pollution des effluents<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18f9733 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18f9733\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-04c18ab\" data-id=\"04c18ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-149b2a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"149b2a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-abd6037\" data-id=\"abd6037\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8311fa7 elementor-widget elementor-widget-heading\" data-id=\"8311fa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Contr\u00f4le de la pollution des effluents<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0a9f264\" data-id=\"0a9f264\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-268efa9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"268efa9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ee3319\" data-id=\"8ee3319\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68cfbf8 elementor-widget elementor-widget-text-editor\" data-id=\"68cfbf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>La m\u00e9thode standard 5210B est la technique de laboratoire la plus largement utilis\u00e9e pour d\u00e9terminer la demande biologique en oxyg\u00e8ne (DBO). Dans un premier temps, un \u00e9chantillon est analys\u00e9 et pr\u00e9par\u00e9 pour cr\u00e9er des conditions favorables \u00e0 la croissance bact\u00e9rienne. Cette pr\u00e9paration peut impliquer l<strong>&lsquo;ajustement du pH, l&rsquo;\u00e9limination du chlore r\u00e9siduel et la r\u00e9duction des niveaux d&rsquo;oxyg\u00e8ne dissous (OD) dans les \u00e9chantillons sursatur\u00e9s.<\/strong> L&rsquo;\u00e9chantillon est ensuite dilu\u00e9 et une quantit\u00e9 appropri\u00e9e de bact\u00e9ries de semence est introduite. Le niveau d&rsquo;OD initial est enregistr\u00e9 et l&rsquo;\u00e9chantillon est incub\u00e9 \u00e0 une temp\u00e9rature de 20\u00b0C pendant une p\u00e9riode de 5 jours.<\/p>\n<p>Une fois la p\u00e9riode de 5 jours \u00e9coul\u00e9e, l&rsquo;\u00e9chantillon est retir\u00e9 de l&rsquo;incubateur et la lecture finale d&rsquo;oxyg\u00e8ne dissous est obtenue. La DBO est calcul\u00e9e en fonction de l&rsquo;\u00e9puisement de l&rsquo;OD et du volume de l&rsquo;\u00e9chantillon, \u00e0 l&rsquo;aide de la formule suivante :<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-617036e elementor-widget elementor-widget-text-editor\" data-id=\"617036e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>DBO<sub>5<\/sub> = DBO mg\/L = [(DO initiale &#8211; DO finale) \u2013 correction des semences] x facteur de dilution<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fdc8db elementor-widget elementor-widget-text-editor\" data-id=\"8fdc8db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Cependant, se fier uniquement aux \u00e9chantillons ponctuels entra\u00eene des retards importants. Lorsque les r\u00e9sultats de la DBO sont re\u00e7us 5 \u00e0 7 jours plus tard, ils offrent g\u00e9n\u00e9ralement une valeur limit\u00e9e pour le contr\u00f4le du processus et l&rsquo;am\u00e9lioration des performances de l&rsquo;usine.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-436783b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"436783b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa5080e elementor-widget elementor-widget-text-editor\" data-id=\"fa5080e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Pour r\u00e9soudre ce probl\u00e8me, il est crucial que les stations d&rsquo;\u00e9puration disposent de solutions pratiques et rentables qui fournissent des informations continues sur la composition et la qualit\u00e9 des eaux us\u00e9es.<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb30211 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb30211\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-84b6839\" data-id=\"84b6839\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-099aa68 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"099aa68\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-db5240a\" data-id=\"db5240a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fca9b3 elementor-widget elementor-widget-heading\" data-id=\"4fca9b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">M\u00e9thodes automatiques de surveillance de la DBO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5a4b479\" data-id=\"5a4b479\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9063d1f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9063d1f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a1cab3f\" data-id=\"a1cab3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-249f302 elementor-widget elementor-widget-text-editor\" data-id=\"249f302\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong><em>Hanna Instruments est la r\u00e9ponse \u00e0 tous vos besoins en \u00e9quipement de titrage !<\/em><\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a66771 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9a66771\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a61168\" data-id=\"4a61168\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59122b1 elementor-widget elementor-widget-heading\" data-id=\"59122b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">HI98198<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-070ce22 elementor-widget elementor-widget-text-editor\" data-id=\"070ce22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Oxym\u00e8tre Optique<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ad4bc3e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad4bc3e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-c4490ed\" data-id=\"c4490ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe9f252 elementor-widget elementor-widget-text-editor\" data-id=\"fe9f252\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>L&rsquo;Oxy\u00e8mtre HI98198 permet de mesurer la concentration d&rsquo;oxyg\u00e8ne dissous sans tracas. La technologie OD optique ne n\u00e9cessite pas de d\u00e9bit minimum, il y a donc moins de d\u00e9rive dans vos lectures.<\/p>\n<p>Parfaite pour le terrain ou pour le laboratoire, la sonde Quick Connect ne n\u00e9cessite aucune membrane, aucune solution de remplissage et aucun temps de pr\u00e9chauffage pour que vous puissiez mesurer sans h\u00e9sitation.<\/p>\n<p>Votre compteur est livr\u00e9 complet dans une mallette de transport robuste et personnalis\u00e9e pour un transport facile.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0872820 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"0872820\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Technologie DO optique pour des lectures rapides et stables, m\u00eame dans des environnements difficiles.<\/li>\n<li>La sonde num\u00e9rique avec technologie Smart Cap \u00e9limine les membranes et les solutions co\u00fbteuses et fastidieuses.<\/li>\n<li>Un corps \u00e9tanche et robuste class\u00e9 IP67 rend ce compteur portable id\u00e9al pour une utilisation sur le terrain.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-97339d5\" data-id=\"97339d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc3de9a elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"bc3de9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"720\" height=\"720\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2023\/07\/HI98198_C-Brighter.jpg\" class=\"attachment-full size-full wp-image-212180\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2023\/07\/HI98198_C-Brighter.jpg 720w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2023\/07\/HI98198_C-Brighter-300x300.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2023\/07\/HI98198_C-Brighter-600x600.jpg 600w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2023\/07\/HI98198_C-Brighter-150x150.jpg 150w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f1a048 elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"6f1a048\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.hannaservice.eu\/advanced-dissolved-oxygen-meter-with-optical-do-probe-opdor-hi6421-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">HI98198 - ACHETER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-67a5614 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"67a5614\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Technologie DO optique pour des lectures rapides et stables, m\u00eame dans des environnements difficiles.<\/li>\n<li>La sonde num\u00e9rique avec technologie Smart Cap \u00e9limine les membranes et les solutions co\u00fbteuses et fastidieuses.<\/li>\n<li>Un corps \u00e9tanche et robuste class\u00e9 IP67 rend ce compteur portable id\u00e9al pour une utilisation sur le terrain.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-98594e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"98594e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d3803d\" data-id=\"4d3803d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78ff6d5 elementor-widget elementor-widget-heading\" data-id=\"78ff6d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">HI6421<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-899b8f7 elementor-widget elementor-widget-text-editor\" data-id=\"899b8f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Appareil de mesure avanc\u00e9 d&rsquo;oxyg\u00e8ne dissous de paillasse avec sonde optique d&rsquo;oxyg\u00e8ne dissous (opdo\u00ae)<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b123f68 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b123f68\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-074d2e7\" data-id=\"074d2e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69f4b3b elementor-widget elementor-widget-text-editor\" data-id=\"69f4b3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>HI6421 est un compteur de paillasse profil\u00e9 avec un grand \u00e9cran tactile, compos\u00e9 d&rsquo;un bo\u00eetier et d&rsquo;un module <strong>int\u00e9gr\u00e9 con\u00e7u pour les mesures d&rsquo;eau douce et sal\u00e9e d&rsquo;oxyg\u00e8ne dissous.<\/strong><\/p>\n<p>HI6421 <a href=\"https:\/\/www.hannaservice.eu\/rugged-optical-dissolved-oxygen-probe-hi764113-product\"><strong>comprend la sonde optique \u00e0 oxyg\u00e8ne dissous HI764113 de Hanna (opdo\u00ae)<\/strong><\/a> bas\u00e9e sur <strong>le principe de l&rsquo;extinction de la fluorescence.<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee11d34 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"ee11d34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Un luminophore \u00e0 base de Pt immobilis\u00e9 est excit\u00e9 par la lumi\u00e8re d&rsquo;une LED bleue et \u00e9met une lumi\u00e8re rouge <\/li>\n<li>Comme l&rsquo;oxyg\u00e8ne interagit avec le luminophore, il r\u00e9duit l&rsquo;intensit\u00e9 et la dur\u00e9e de vie de la luminescence <\/li>\n<li>La dur\u00e9e de vie de la luminescence est mesur\u00e9e par un photod\u00e9tecteur et est utilis\u00e9e pour calculer la concentration en oxyg\u00e8ne dissous<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-046cbce\" data-id=\"046cbce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f0590c elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"7f0590c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"720\" height=\"720\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2023\/07\/HI6421P-Left-Low.jpg\" class=\"attachment-full size-full wp-image-212187\" alt=\"\" srcset=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2023\/07\/HI6421P-Left-Low.jpg 720w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2023\/07\/HI6421P-Left-Low-300x300.jpg 300w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2023\/07\/HI6421P-Left-Low-600x600.jpg 600w, https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2023\/07\/HI6421P-Left-Low-150x150.jpg 150w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b840978 elementor-align-center elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"b840978\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.hannainstruments.at\/advanced-dissolved-oxygen-meter-with-optical-do-probe-opdor-hi6421-product\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">HI6421 - ACHETER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-f466e74 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"f466e74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Un luminophore \u00e0 base de Pt immobilis\u00e9 est excit\u00e9 par la lumi\u00e8re d&rsquo;une LED bleue et \u00e9met une lumi\u00e8re rouge <\/li>\n<li>Comme l&rsquo;oxyg\u00e8ne interagit avec le luminophore, il r\u00e9duit l&rsquo;intensit\u00e9 et la dur\u00e9e de vie de la luminescence <\/li>\n<li>La dur\u00e9e de vie de la luminescence est mesur\u00e9e par un photod\u00e9tecteur et est utilis\u00e9e pour calculer la concentration en oxyg\u00e8ne dissous<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0dafa63 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0dafa63\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e0bc4a\" data-id=\"7e0bc4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfc8037 elementor-widget elementor-widget-text-editor\" data-id=\"cfc8037\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: center;\"><strong>Avoir des questions?<\/strong><\/h3>\n<p style=\"text-align: center;\">Contactez un sp\u00e9cialiste technique <a class=\"keychainify-checked\" href=\"mailto:info@hannaservice.eu\"><strong>Hanna \u00e0 info@hannaservice.eu<\/strong><\/a> ou en utilisant notre <strong><a href=\"https:\/\/www.hannaservice.eu\/contact-us\" target=\"_blank\" rel=\"noopener\" data-wplink-edit=\"true\">formulaire de contact<\/a><\/strong>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45cdbbf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45cdbbf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9599fb3\" data-id=\"9599fb3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0220f9a elementor-widget elementor-widget-text-editor\" data-id=\"0220f9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>SOURCES:<\/strong><\/p>\n<p style=\"padding-left: 40px;\"><a href=\"https:\/\/www.researchgate.net\/profile\/Sulivan-Jouanneau-2\">Sulivan Jouanneau<\/a>, <em>M\u00e9thodes d&rsquo;\u00e9valuation de la demande biochimique en oxyg\u00e8ne (DBO)<\/em>, novembre 2013<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ad3b05 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ad3b05\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d586a43\" data-id=\"d586a43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3aeaa18 elementor-widget elementor-widget-image\" data-id=\"3aeaa18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"252\" height=\"74\" src=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2022\/08\/Logo-Hanna-Inst.jpg\" class=\"attachment-large size-large wp-image-177342\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67b6171 elementor-widget elementor-widget-text-editor\" data-id=\"67b6171\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Avec un excellent produit<br \/>Venez de grands r\u00e9sultats<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-207f3ef\" data-id=\"207f3ef\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a6e7efc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a6e7efc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-600ebbc\" data-id=\"600ebbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c06b4b elementor-widget elementor-widget-heading\" data-id=\"9c06b4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Service <\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-40825b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40825b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8b5544a\" data-id=\"8b5544a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcd9fa6 elementor-widget elementor-widget-heading\" data-id=\"fcd9fa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Entra\u00eenement<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f420710 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f420710\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ba8d3f6\" data-id=\"ba8d3f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7821cc6 elementor-widget elementor-widget-heading\" data-id=\"7821cc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rapair<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8fe4ae9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8fe4ae9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8c4d98f\" data-id=\"8c4d98f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d809f1 elementor-widget elementor-widget-heading\" data-id=\"8d809f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Maintenance<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La demande biologique en oxyg\u00e8ne (DBO) est une mesure de la quantit\u00e9 d&rsquo;oxyg\u00e8ne dissous (OD) [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":212161,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[392],"tags":[],"class_list":["post-212324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industrie-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comprendre l&#039;importance de la DBO : mesurer les niveaux d&#039;oxyg\u00e8ne dans l&#039;eau - Hanna Instruments Maroc<\/title>\n<meta name=\"description\" content=\"La demande biologique en oxyg\u00e8ne est un param\u00e8tre important dans l&#039;\u00e9valuation de la qualit\u00e9 de l&#039;eau. Hanna Instruments est la r\u00e9ponse \u00e0 tous vos besoins en \u00e9quipement de titrage !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment choisir la bonne \u00e9lectrode pour votre \u00e9chantillon ?\" \/>\n<meta property=\"og:description\" content=\"LES \u00c9CHANTILLONS PEUVENT \u00caTRE DIFFICILES, MAIS LA MESURE PEUT \u00caTRE FACILE. Recevoir des valeurs correctes et stables peut cependant \u00eatre difficile, en particulier dans certains \u00e9chantillons (comme les aliments, le sol, les cr\u00e8mes, la peinture, les \u00e9chantillons \u00e0 pH \u00e9lev\u00e9, etc.). Il est important de comprendre ce que Le pH signifie comment fonctionne une \u00e9lectrode de pH et comment la mesure peut \u00eatre plus facile en utilisant la bonne \u00e9lectrode. Vous ne savez pas quelle \u00e9lectrode serait la meilleure pour votre \u00e9chantillon ? Vous pouvez toujours nous contacter ou en savoir plus sur le lien : https:\/\/blog. hannaservice.eu\/choisissez-la-bonne-\u00e9lectrode-pour-vos-\u00e9chantillons\/#pH #measuring #analyse #CQ #mesure du pH #pHm\u00e8tre #pHtesteur #calibrage #nettoyage #conditionnement #\u00e9lectrode #hannainstruments\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/\" \/>\n<meta property=\"og:site_name\" content=\"Hanna Instruments Maroc\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-26T14:06:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-16T08:08:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2023\/07\/BOD-post-facebook-morocco.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alan Curtis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alan Curtis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\\\/\"},\"author\":{\"name\":\"Alan Curtis\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/person\\\/675987b8b5fd7dfbc3ccca6b0bd2d486\"},\"headline\":\"Comprendre l&rsquo;importance de la DBO : mesurer les niveaux d&rsquo;oxyg\u00e8ne dans l&rsquo;eau\",\"datePublished\":\"2023-07-26T14:06:13+00:00\",\"dateModified\":\"2023-08-16T08:08:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\\\/\"},\"wordCount\":1443,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Shutterstock_1805712724.jpg\",\"articleSection\":[\"Industrie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\\\/\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\\\/\",\"name\":\"Comprendre l'importance de la DBO : mesurer les niveaux d'oxyg\u00e8ne dans l'eau - Hanna Instruments Maroc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Shutterstock_1805712724.jpg\",\"datePublished\":\"2023-07-26T14:06:13+00:00\",\"dateModified\":\"2023-08-16T08:08:22+00:00\",\"description\":\"La demande biologique en oxyg\u00e8ne est un param\u00e8tre important dans l'\u00e9valuation de la qualit\u00e9 de l'eau. Hanna Instruments est la r\u00e9ponse \u00e0 tous vos besoins en \u00e9quipement de titrage !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Shutterstock_1805712724.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Shutterstock_1805712724.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog home\",\"item\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comprendre l&rsquo;importance de la DBO : mesurer les niveaux d&rsquo;oxyg\u00e8ne dans l&rsquo;eau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\",\"name\":\"Hanna Instruments Africa\",\"description\":\"pH M\u00e8tres, Photom\u00e8tres, Titrateurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#organization\",\"name\":\"Hanna Instruments\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/hs-logo.png\",\"contentUrl\":\"https:\\\/\\\/blog.hannaservice.eu\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/hs-logo.png\",\"width\":733,\"height\":225,\"caption\":\"Hanna Instruments\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/#\\\/schema\\\/person\\\/675987b8b5fd7dfbc3ccca6b0bd2d486\",\"name\":\"Alan Curtis\",\"sameAs\":[\"https:\\\/\\\/blog.hannaservice.eu\\\/\"],\"url\":\"https:\\\/\\\/blog.hannaservice.eu\\\/fr\\\/author\\\/alancurtis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comprendre l'importance de la DBO : mesurer les niveaux d'oxyg\u00e8ne dans l'eau - Hanna Instruments Maroc","description":"La demande biologique en oxyg\u00e8ne est un param\u00e8tre important dans l'\u00e9valuation de la qualit\u00e9 de l'eau. Hanna Instruments est la r\u00e9ponse \u00e0 tous vos besoins en \u00e9quipement de titrage !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment choisir la bonne \u00e9lectrode pour votre \u00e9chantillon ?","og_description":"LES \u00c9CHANTILLONS PEUVENT \u00caTRE DIFFICILES, MAIS LA MESURE PEUT \u00caTRE FACILE. Recevoir des valeurs correctes et stables peut cependant \u00eatre difficile, en particulier dans certains \u00e9chantillons (comme les aliments, le sol, les cr\u00e8mes, la peinture, les \u00e9chantillons \u00e0 pH \u00e9lev\u00e9, etc.). Il est important de comprendre ce que Le pH signifie comment fonctionne une \u00e9lectrode de pH et comment la mesure peut \u00eatre plus facile en utilisant la bonne \u00e9lectrode. Vous ne savez pas quelle \u00e9lectrode serait la meilleure pour votre \u00e9chantillon ? Vous pouvez toujours nous contacter ou en savoir plus sur le lien : https:\/\/blog. hannaservice.eu\/choisissez-la-bonne-\u00e9lectrode-pour-vos-\u00e9chantillons\/#pH #measuring #analyse #CQ #mesure du pH #pHm\u00e8tre #pHtesteur #calibrage #nettoyage #conditionnement #\u00e9lectrode #hannainstruments","og_url":"https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/","og_site_name":"Hanna Instruments Maroc","article_published_time":"2023-07-26T14:06:13+00:00","article_modified_time":"2023-08-16T08:08:22+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2023\/07\/BOD-post-facebook-morocco.png","type":"image\/png"}],"author":"Alan Curtis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Alan Curtis","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/#article","isPartOf":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/"},"author":{"name":"Alan Curtis","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/person\/675987b8b5fd7dfbc3ccca6b0bd2d486"},"headline":"Comprendre l&rsquo;importance de la DBO : mesurer les niveaux d&rsquo;oxyg\u00e8ne dans l&rsquo;eau","datePublished":"2023-07-26T14:06:13+00:00","dateModified":"2023-08-16T08:08:22+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/"},"wordCount":1443,"publisher":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2023\/07\/Shutterstock_1805712724.jpg","articleSection":["Industrie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/","url":"https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/","name":"Comprendre l'importance de la DBO : mesurer les niveaux d'oxyg\u00e8ne dans l'eau - Hanna Instruments Maroc","isPartOf":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/#primaryimage"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2023\/07\/Shutterstock_1805712724.jpg","datePublished":"2023-07-26T14:06:13+00:00","dateModified":"2023-08-16T08:08:22+00:00","description":"La demande biologique en oxyg\u00e8ne est un param\u00e8tre important dans l'\u00e9valuation de la qualit\u00e9 de l'eau. Hanna Instruments est la r\u00e9ponse \u00e0 tous vos besoins en \u00e9quipement de titrage !","breadcrumb":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/#primaryimage","url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2023\/07\/Shutterstock_1805712724.jpg","contentUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2023\/07\/Shutterstock_1805712724.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/blog.hannaservice.eu\/fr\/comprendre-limportance-de-la-dbo-mesurer-les-niveaux-doxygene-dans-leau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog home","item":"https:\/\/blog.hannaservice.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Comprendre l&rsquo;importance de la DBO : mesurer les niveaux d&rsquo;oxyg\u00e8ne dans l&rsquo;eau"}]},{"@type":"WebSite","@id":"https:\/\/blog.hannaservice.eu\/fr\/#website","url":"https:\/\/blog.hannaservice.eu\/fr\/","name":"Hanna Instruments Africa","description":"pH M\u00e8tres, Photom\u00e8tres, Titrateurs","publisher":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.hannaservice.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.hannaservice.eu\/fr\/#organization","name":"Hanna Instruments","url":"https:\/\/blog.hannaservice.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/01\/hs-logo.png","contentUrl":"https:\/\/blog.hannaservice.eu\/wp-content\/uploads\/2021\/01\/hs-logo.png","width":733,"height":225,"caption":"Hanna Instruments"},"image":{"@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.hannaservice.eu\/fr\/#\/schema\/person\/675987b8b5fd7dfbc3ccca6b0bd2d486","name":"Alan Curtis","sameAs":["https:\/\/blog.hannaservice.eu\/"],"url":"https:\/\/blog.hannaservice.eu\/fr\/author\/alancurtis\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/212324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/comments?post=212324"}],"version-history":[{"count":18,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/212324\/revisions"}],"predecessor-version":[{"id":213800,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/posts\/212324\/revisions\/213800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/media\/212161"}],"wp:attachment":[{"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/media?parent=212324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/categories?post=212324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.hannaservice.eu\/fr\/wp-json\/wp\/v2\/tags?post=212324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}